{"id":9735,"date":"2026-06-23T14:39:22","date_gmt":"2026-06-23T17:39:22","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/comissao-aprova-criacao-de-cadastro-no-sus-para-mulheres-vulneraveis-com-risco-de-cancer-noticias\/"},"modified":"2026-06-23T14:39:22","modified_gmt":"2026-06-23T17:39:22","slug":"comissao-aprova-criacao-de-cadastro-no-sus-para-mulheres-vulneraveis-com-risco-de-cancer-noticias","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/comissao-aprova-criacao-de-cadastro-no-sus-para-mulheres-vulneraveis-com-risco-de-cancer-noticias\/","title":{"rendered":"Comiss\u00e3o aprova cria\u00e7\u00e3o de cadastro no SUS para mulheres vulner\u00e1veis com risco de c\u00e2ncer &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"g-artigo__data-hora\">\n\t\t\t\t\t\t\t\t\t\t\t23\/06\/2026 &#8211; 12:20 \u00a0\n\t\t\t\t\t\t\t\t\t\t<\/p>\n<div id=\"image-container-1277346\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1277346\">\n<p><em>Bruno Spada \/ C\u00e2mara dos Deputados<\/em><\/p>\n<p>Laura Carneiro recomendou a aprova\u00e7\u00e3o da proposta<\/p>\n<\/p><\/div>\n<p>A Comiss\u00e3o de Defesa dos Direitos da Mulher da C\u00e2mara dos Deputados aprovou o Projeto de Lei 2756\/25, que cria um cadastro no Sistema \u00danico de Sa\u00fade (SUS) para identificar e acompanhar mulheres em situa\u00e7\u00e3o de risco ou vulnerabilidade social com maiores chances de desenvolver c\u00e2ncer, em especial de mama e de colo do \u00fatero.<\/p>\n<p>O cadastro incluir\u00e1 mulheres que preencham pelo menos um dos seguintes crit\u00e9rios:<\/p>\n<ul>\n<li>morar em \u00e1reas de alta vulnerabilidade social, conforme indicadores do IBGE ou do <span id=\"4330\" class=\"termoGlossario\" title=\"Instrumento de coleta de dados que identifica e caracteriza fam\u00edlias com renda mensal de at\u00e9 meio sal\u00e1rio m\u00ednimo por pessoa. Os dados obtidos por meio do Cad\u00danico s\u00e3o consolidados e utilizados, obrigatoriamente, na sele\u00e7\u00e3o de benefici\u00e1rios dos programas sociais do Governo Federal. Governos estaduais e municipais tamb\u00e9m podem usar os dados do cadastro para analisar o perfil socioecon\u00f4mico da popula\u00e7\u00e3o e, desse modo, implantar pol\u00edticas direcionadas \u00e0s necessidades locais.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">Cad\u00danico<\/span>;<\/li>\n<li>integrar popula\u00e7\u00f5es tradicionais, comunidades quilombolas, ind\u00edgenas ou ribeirinhas;<\/li>\n<li>estar em situa\u00e7\u00e3o de rua ou abrigamento institucional;<\/li>\n<li>ter hist\u00f3rico familiar de c\u00e2ncer ginecol\u00f3gico ou apresentar fatores cl\u00ednicos de risco; e<\/li>\n<li>estar presa.<\/li>\n<\/ul>\n<p>O Minist\u00e9rio da Sa\u00fade poder\u00e1 determinar outras condi\u00e7\u00f5es em regulamento.<\/p>\n<p>A proposta \u00e9 da deputada Rog\u00e9ria Santos (Republicanos-BA). A relatora, deputada Laura Carneiro (PSD-RJ), recomendou a aprova\u00e7\u00e3o.<\/p>\n<p><strong>Barreiras<br \/><\/strong>Laura Carneiro argumenta que, para as pessoas vulner\u00e1veis, os problemas decorrentes do c\u00e2ncer v\u00e3o al\u00e9m da doen\u00e7a f\u00edsica e envolvem a falta de recursos econ\u00f4micos e de redes de apoio.<\/p>\n<p>\u201cO cadastro nacional tem como objetivos promover o rastreamento, o acompanhamento m\u00e9dico e o cuidado priorit\u00e1rio de mulheres que enfrentam m\u00faltiplas barreiras de acesso \u00e0 preven\u00e7\u00e3o e ao tratamento do c\u00e2ncer\u201d, explica Laura Carneiro.<\/p>\n<p>\u201cS\u00e3o essas m\u00faltiplas barreiras que precisam ser superadas se quisermos oferecer para essa popula\u00e7\u00e3o condi\u00e7\u00f5es mais dignas de tratamento do c\u00e2ncer no nosso pa\u00eds.\u201d<\/p>\n<p><strong>Finalidades<br \/><\/strong>O programa ter\u00e1 como finalidade:<\/p>\n<ul>\n<li>assegurar o rastreamento peri\u00f3dico e priorit\u00e1rio das mulheres cadastradas;<\/li>\n<li>garantir acesso facilitado a exames de triagem, diagn\u00f3stico, bi\u00f3psias, acompanhamento e tratamento oncol\u00f3gico no SUS;<\/li>\n<li>integrar os dados com os sistemas de informa\u00e7\u00e3o em sa\u00fade para monitorar pol\u00edticas p\u00fablicas; e<\/li>\n<li>apoiar programas de navega\u00e7\u00e3o do paciente e acompanhamento ativo em toda a linha de cuidado oncol\u00f3gico.<\/li>\n<\/ul>\n<p><strong>Visitas peri\u00f3dicas<br \/><\/strong>A comiss\u00e3o acolheu uma modifica\u00e7\u00e3o <a href=\"http:\/\/camara.leg.br\/noticias\/1250496-COMISSAO-APROVA-PROJETO-QUE-CRIA-CADASTRO-NO-SUS-DE-MULHERES-EM-SITUACAO-DE-VULNERABILIDADE-COM-RISCO-DE-CANCER\">aprovada na Comiss\u00e3o de Sa\u00fade<\/a> para prever o acompanhamento por meio de visitas peri\u00f3dicas de equipes de assist\u00eancia social.<\/p>\n<p>O objetivo \u00e9 garantir o suporte adequado e os devidos encaminhamentos \u00e0s mulheres em situa\u00e7\u00e3o de vulnerabilidade oncol\u00f3gica.<\/p>\n<p><strong>Pr\u00f3ximos passos<br \/><\/strong>O projeto, que tramita em <span id=\"4322\" class=\"termoGlossario\" title=\"Rito de tramita\u00e7\u00e3o pelo qual o projeto \u00e9 votado apenas pelas comiss\u00f5es designadas para analis\u00e1-lo, dispensada a delibera\u00e7\u00e3o do Plen\u00e1rio. O projeto perde o car\u00e1ter conclusivo se houver decis\u00e3o divergente entre as comiss\u00f5es ou se, independentemente de ser aprovado ou rejeitado, houver recurso assinado por 52 deputados para a aprecia\u00e7\u00e3o da mat\u00e9ria no Plen\u00e1rio.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">car\u00e1ter conclusivo<\/span>, ainda ser\u00e1 analisado pelas comiss\u00f5es de Finan\u00e7as e Tributa\u00e7\u00e3o; e de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania.<\/p>\n<p>Para virar lei, precisa ser aprovado pela C\u00e2mara e pelo Senado.<\/p>\n<p>\u00a0<\/p>\n<p>\t\t\t\t<iframe class=\"infografico-container\" style=\"width: 100%; height: 100%;\" src=\"https:\/\/www.camara.leg.br\/internet\/agencia\/infograficos-html5\/cancer-mama-brasil-numeros\/index.html\" frameborder=\"0\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Da Reportagem \u2013 NN<br \/>Edi\u00e7\u00e3o \u2013 Natalia Doederlein<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1284361-comissao-aprova-criacao-de-cadastro-no-sus-para-mulheres-vulneraveis-com-risco-de-cancer\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>23\/06\/2026 &#8211; 12:20 \u00a0 Bruno Spada \/ C\u00e2mara dos Deputados Laura Carneiro recomendou a aprova\u00e7\u00e3o da proposta A Comiss\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[26],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9735"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=9735"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/9080"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=9735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=9735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=9735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}