{"id":9709,"date":"2026-06-20T20:06:48","date_gmt":"2026-06-20T23:06:48","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/comissao-aprova-oferta-de-orientacao-parental-nas-redes-publicas-de-saude-e-assistencia-social-noticias\/"},"modified":"2026-06-20T20:06:48","modified_gmt":"2026-06-20T23:06:48","slug":"comissao-aprova-oferta-de-orientacao-parental-nas-redes-publicas-de-saude-e-assistencia-social-noticias","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/comissao-aprova-oferta-de-orientacao-parental-nas-redes-publicas-de-saude-e-assistencia-social-noticias\/","title":{"rendered":"Comiss\u00e3o aprova oferta de orienta\u00e7\u00e3o parental nas redes p\u00fablicas de sa\u00fade e assist\u00eancia social &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"g-artigo__data-hora\">\n\t\t\t\t\t\t\t\t\t\t\t19\/06\/2026 &#8211; 09:42 \u00a0\n\t\t\t\t\t\t\t\t\t\t<\/p>\n<div id=\"image-container-1283928\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1283928\">\n<p><em>Kayo Magalh\u00e3es \/ C\u00e2mara dos Deputados<\/em><\/p>\n<p>Rog\u00e9ria Santos \u00e9 a relatora da proposta<\/p>\n<\/p><\/div>\n<p>A Comiss\u00e3o de Previd\u00eancia, Assist\u00eancia Social, Inf\u00e2ncia, Adolesc\u00eancia e Fam\u00edlia da C\u00e2mara dos Deputados aprovou o Projeto de Lei 574\/26, da deputada Laura Carneiro (PSD-RJ), que determina que estados, o Distrito Federal e munic\u00edpios ofere\u00e7am servi\u00e7os de orienta\u00e7\u00e3o e apoio em educa\u00e7\u00e3o parental \u00e0 popula\u00e7\u00e3o.<\/p>\n<p>Pela proposta, esses servi\u00e7os dever\u00e3o ser disponibilizados nas redes p\u00fablicas de sa\u00fade e de assist\u00eancia social, em espa\u00e7os escolares e, quando cab\u00edvel, em espa\u00e7os p\u00fablicos e privados conveniados que atendam crian\u00e7as, adolescentes e suas fam\u00edlias. O texto inclui a obriga\u00e7\u00e3o na <a class=\"linkLegislacao\" href=\"https:\/\/www2.camara.gov.br\/legin\/fed\/lei\/2024\/lei-14826-20-marco-2024-795391-norma-pl.html\" target=\"_blank\" rel=\"noopener noreferrer\">Lei 14.826\/24<\/a>, que institui a parentalidade positiva.<\/p>\n<p><strong>Profissionais<\/strong><br \/>O projeto define que os servi\u00e7os ser\u00e3o executados, preferencialmente, por educadores parentais. Tamb\u00e9m poder\u00e3o atuar profissionais das \u00e1reas de sa\u00fade, educa\u00e7\u00e3o e assist\u00eancia social, desde que tenham forma\u00e7\u00e3o espec\u00edfica ou certifica\u00e7\u00e3o em estrat\u00e9gias de parentalidade positiva, preven\u00e7\u00e3o de viol\u00eancia e neuroci\u00eancia do desenvolvimento infantil.<\/p>\n<p>Os profissionais de educa\u00e7\u00e3o parental n\u00e3o poder\u00e3o exercer atividades exclusivas de profiss\u00f5es regulamentadas, especialmente as de natureza cl\u00ednica ou terap\u00eautica \u2014 como a psicologia cl\u00ednica. A atua\u00e7\u00e3o ser\u00e1 apenas preventiva e pedag\u00f3gica, voltada ao fortalecimento dos v\u00ednculos familiares e \u00e0 capacita\u00e7\u00e3o dos cuidadores.<\/p>\n<p><strong>Preven\u00e7\u00e3o \u00e0 viol\u00eancia<\/strong><br \/>Para Laura Carneiro, a lei de 2024 representou um marco ao instituir a parentalidade positiva, mas a previs\u00e3o legal, por si s\u00f3, \u00e9 insuficiente sem servi\u00e7os que cheguem \u00e0s fam\u00edlias, especialmente \u00e0s mais vulner\u00e1veis. &#8220;O fortalecimento das fam\u00edlias \u00e9 a forma mais eficaz de proteger a inf\u00e2ncia&#8221;, afirmou.<\/p>\n<p>A relatora, deputada Rog\u00e9ria Santos (Republicanos-BA), afirmou que est\u00e1 alinhada \u00e0 economia do cuidado, dado que o ato de cuidar, historicamente invisibilizado e gerador de grande sobrecarga, recai majoritariamente sobre as mulheres, e exige solu\u00e7\u00f5es legais concretas para a sua provis\u00e3o e suporte.<\/p>\n<p>&#8220;Investir na educa\u00e7\u00e3o familiar preventiva significa promover a sustentabilidade das pol\u00edticas sociais, reduzindo futuramente a demanda por tratamentos de alta complexidade e a atua\u00e7\u00e3o do sistema de justi\u00e7a criminal&#8221;, disse Santos.<\/p>\n<p>Cerca de 200 casos de viol\u00eancia f\u00edsica contra crian\u00e7as e adolescentes s\u00e3o notificados diariamente nas unidades de sa\u00fade do pa\u00eds, segundo dados da Sociedade Brasileira de Pediatria. Levantamento do Minist\u00e9rio dos Direitos Humanos e da Cidadania indica que 81% dos casos de viol\u00eancia contra crian\u00e7as e adolescentes ocorrem em casa.<\/p>\n<p><strong>Pr\u00f3ximos passos<\/strong><br \/>A proposta ainda ser\u00e1 analisada, em <span id=\"4322\" class=\"termoGlossario\" title=\"Rito de tramita\u00e7\u00e3o pelo qual o projeto \u00e9 votado apenas pelas comiss\u00f5es designadas para analis\u00e1-lo, dispensada a delibera\u00e7\u00e3o do Plen\u00e1rio. O projeto perde o car\u00e1ter conclusivo se houver decis\u00e3o divergente entre as comiss\u00f5es ou se, independentemente de ser aprovado ou rejeitado, houver recurso assinado por 52 deputados para a aprecia\u00e7\u00e3o da mat\u00e9ria no Plen\u00e1rio.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">car\u00e1ter conclusivo<\/span>, pela Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania. Para virar lei, precisa ser aprovada pela C\u00e2mara e pelo Senado.<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Reportagem \u2013 Tiago Miranda<br \/>Edi\u00e7\u00e3o \u2013 Rachel Librelon<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1283799-comissao-aprova-oferta-de-orientacao-parental-nas-redes-publicas-de-saude-e-assistencia-social\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>19\/06\/2026 &#8211; 09:42 \u00a0 Kayo Magalh\u00e3es \/ C\u00e2mara dos Deputados Rog\u00e9ria Santos \u00e9 a relatora da proposta A Comiss\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9710,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9709"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=9709"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9709\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/9710"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=9709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=9709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=9709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}