{"id":9697,"date":"2026-06-20T05:45:10","date_gmt":"2026-06-20T08:45:10","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/comissao-aprova-inclusao-de-internet-nas-campanhas-de-prevencao-a-violencia-domestica-noticias\/"},"modified":"2026-06-20T05:45:10","modified_gmt":"2026-06-20T08:45:10","slug":"comissao-aprova-inclusao-de-internet-nas-campanhas-de-prevencao-a-violencia-domestica-noticias","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/comissao-aprova-inclusao-de-internet-nas-campanhas-de-prevencao-a-violencia-domestica-noticias\/","title":{"rendered":"Comiss\u00e3o aprova inclus\u00e3o de internet nas campanhas de preven\u00e7\u00e3o \u00e0 viol\u00eancia dom\u00e9stica &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<div>\n<p class=\"g-artigo__data-hora\">\n\t\t\t\t\t\t\t\t\t\t\t19\/06\/2026 &#8211; 16:00 \u00a0\n\t\t\t\t\t\t\t\t\t\t<\/p>\n<div id=\"image-container-1284124\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1284124\">\n<p><em>Vinicius Loures\/C\u00e2mara dos Deputados<\/em><\/p>\n<p>Silvye Alves \u00e9 a relatora do projeto<\/p>\n<\/p><\/div>\n<p>A Comiss\u00e3o de Defesa dos Direitos da Mulher da C\u00e2mara dos Deputados aprovou o Projeto de Lei 4281\/25, da deputada Franciane Bayer (Republicanos-RS), que exige a veicula\u00e7\u00e3o de campanhas educativas de preven\u00e7\u00e3o \u00e0 viol\u00eancia dom\u00e9stica e familiar contra a mulher tamb\u00e9m em aplica\u00e7\u00f5es de internet, com formatos e linguagens adequados ao ambiente digital.<\/p>\n<p>A proposta altera a <a class=\"linkLegislacao\" href=\"https:\/\/www2.camara.gov.br\/legin\/fed\/lei\/2006\/lei-11340-7-agosto-2006-545133-norma-pl.html\" target=\"_blank\" rel=\"noopener noreferrer\">Lei Maria da Penha <\/a>para incluir essa exig\u00eancia. A norma j\u00e1 estabelece a necessidade de campanhas educativas como parte da pol\u00edtica p\u00fablica de enfrentamento \u00e0 viol\u00eancia de g\u00eanero.<\/p>\n<p>A proposta n\u00e3o define plataformas ou formatos espec\u00edficos. Segundo a deputada, os h\u00e1bitos de consumo de conte\u00fado mudam rapidamente e uma lista fechada poderia tornar a lei obsoleta.<\/p>\n<p>O projeto tamb\u00e9m inclui a obriga\u00e7\u00e3o de monitorar e avaliar a efetividade das a\u00e7\u00f5es previstas na lei. Segundo Bayer, a medida permitir\u00e1 ao poder p\u00fablico identificar o que funciona, corrigir estrat\u00e9gias falhas e otimizar o uso de recursos.<\/p>\n<p><strong>Lacuna<br \/><\/strong>A relatora, deputada Silvye Alves (Uni\u00e3o-GO), recomendou a aprova\u00e7\u00e3o da proposta. &#8220;Trata-se de medida alinhada com o princ\u00edpio da efici\u00eancia da administra\u00e7\u00e3o p\u00fablica, ao buscar maior desempenho das pol\u00edticas p\u00fablicas por meio do uso de canais contempor\u00e2neos de comunica\u00e7\u00e3o&#8221;, disse.<\/p>\n<p>Silvye Alves elogiou a inclus\u00e3o do monitoramento e da avalia\u00e7\u00e3o da efetividade das a\u00e7\u00f5es. &#8220;Refor\u00e7a a ado\u00e7\u00e3o de pr\u00e1ticas de gest\u00e3o baseadas em evid\u00eancias, permitindo o aprimoramento cont\u00ednuo das pol\u00edticas p\u00fablicas e maior controle social sobre seus resultados&#8221;, declarou.<\/p>\n<p><strong>Pr\u00f3ximos passos<\/strong><br \/>A proposta ainda ser\u00e1 analisada, em <span id=\"4322\" class=\"termoGlossario\" title=\"Rito de tramita\u00e7\u00e3o pelo qual o projeto \u00e9 votado apenas pelas comiss\u00f5es designadas para analis\u00e1-lo, dispensada a delibera\u00e7\u00e3o do Plen\u00e1rio. O projeto perde o car\u00e1ter conclusivo se houver decis\u00e3o divergente entre as comiss\u00f5es ou se, independentemente de ser aprovado ou rejeitado, houver recurso assinado por 52 deputados para a aprecia\u00e7\u00e3o da mat\u00e9ria no Plen\u00e1rio.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">car\u00e1ter conclusivo<\/span>, pela Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania. Para virar lei, precisa ser aprovada pela C\u00e2mara e pelo Senado.<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Reportagem \u2013 Tiago Miranda<br \/>Edi\u00e7\u00e3o \u2013 Rachel Librelon<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1283782-comissao-aprova-inclusao-de-internet-nas-campanhas-de-prevencao-a-violencia-domestica\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>19\/06\/2026 &#8211; 16:00 \u00a0 Vinicius Loures\/C\u00e2mara dos Deputados Silvye Alves \u00e9 a relatora do projeto A Comiss\u00e3o de Defesa dos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9697"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=9697"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9697\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/9698"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=9697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=9697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=9697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}