{"id":9695,"date":"2026-06-20T03:41:08","date_gmt":"2026-06-20T06:41:08","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/comissao-aprova-projeto-que-autoriza-extensao-de-estagio-apos-conclusao-de-curso-superior-noticias\/"},"modified":"2026-06-20T03:41:08","modified_gmt":"2026-06-20T06:41:08","slug":"comissao-aprova-projeto-que-autoriza-extensao-de-estagio-apos-conclusao-de-curso-superior-noticias","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/comissao-aprova-projeto-que-autoriza-extensao-de-estagio-apos-conclusao-de-curso-superior-noticias\/","title":{"rendered":"Comiss\u00e3o aprova projeto que autoriza extens\u00e3o de est\u00e1gio ap\u00f3s conclus\u00e3o de curso superior &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<div>\n<p class=\"g-artigo__data-hora\">\n\t\t\t\t\t\t\t\t\t\t\t19\/06\/2026 &#8211; 16:25 \u00a0\n\t\t\t\t\t\t\t\t\t\t<\/p>\n<div id=\"image-container-1284175\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1284175\">\n<p><em>Kayo Magalh\u00e3es\/C\u00e2mara dos Deputados<\/em><\/p>\n<p>Luiz Carlos Motta, relator do projeto de lei<\/p>\n<\/p><\/div>\n<p>A Comiss\u00e3o de Educa\u00e7\u00e3o da C\u00e2mara dos Deputados aprovou projeto de lei que garante a continuidade do contrato de est\u00e1gio mesmo ap\u00f3s a formatura do estudante, desde que a vaga seja na empresa em que estava vinculado durante a fase de estudos.<\/p>\n<p>O texto limita em 12 meses a dura\u00e7\u00e3o do est\u00e1gio ap\u00f3s a conclus\u00e3o do curso. A regra prev\u00ea teto de dois anos para a perman\u00eancia na empresa, com exce\u00e7\u00e3o para pessoas com defici\u00eancia.<\/p>\n<p>O est\u00e1gio poder\u00e1 ser realizado de forma presencial, a dist\u00e2ncia ou h\u00edbrida.<\/p>\n<p>Por recomenda\u00e7\u00e3o do relator, deputado Luiz Carlos Motta (PL-SP), o colegiado aprovou o <span id=\"4098\" class=\"termoGlossario\" title=\"Nome que se d\u00e1 ao texto que altera substancialmente o conte\u00fado original da proposta. O substitutivo \u00e9 apresentado pelo relator e tem prefer\u00eancia na vota\u00e7\u00e3o sobre o projeto original.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">substitutivo<\/span> da Comiss\u00e3o de Trabalho ao Projeto de Lei 7021\/17, de autoria do deputado Alex Manente (Cidadania-SP), com altera\u00e7\u00f5es.<\/p>\n<p>Segundo o relator, a proposta ajuda o estagi\u00e1rio na fase de transi\u00e7\u00e3o para o mercado de trabalho. &#8220;O jovem obt\u00e9m a gradua\u00e7\u00e3o, mas n\u00e3o tem a experi\u00eancia exigida pelas empresas para a primeira contrata\u00e7\u00e3o na \u00e1rea de forma\u00e7\u00e3o. O problema resulta na aus\u00eancia de viv\u00eancia profissional&#8221;, afirmou.<\/p>\n<p>Luiz Carlos Motta cita pesquisa do Instituto Brasileiro de Geografia e Estat\u00edstica (<span id=\"4178\" class=\"termoGlossario\" title=\"\u00d3rg\u00e3o da administra\u00e7\u00e3o p\u00fablica federal, subordinado ao Minist\u00e9rio do Planejamento, Or\u00e7amento e Gest\u00e3o. \u00c9 o principal provedor de dados oficiais do Pa\u00eds, sendo respons\u00e1vel pela produ\u00e7\u00e3o, an\u00e1lise, pesquisa e dissemina\u00e7\u00e3o de informa\u00e7\u00f5es de natureza estat\u00edstica (demogr\u00e1fica, social e econ\u00f4mica), geogr\u00e1fica, cartogr\u00e1fica, geod\u00e9sica e ambiental.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">IBGE<\/span>) pela qual a informalidade atinge 38,5% dos jovens entre 18 e 19 anos em 2026.<\/p>\n<p>O texto aprovado pro\u00edbe a gest\u00e3o de contratos de est\u00e1gio por empresas terceirizadas, bem como a cobran\u00e7a de taxas aos envolvidos no acordo de trabalho.<\/p>\n<p><strong>Pr\u00f3ximos passos<\/strong><br \/>A proposta tramita em <span id=\"4322\" class=\"termoGlossario\" title=\"Rito de tramita\u00e7\u00e3o pelo qual o projeto \u00e9 votado apenas pelas comiss\u00f5es designadas para analis\u00e1-lo, dispensada a delibera\u00e7\u00e3o do Plen\u00e1rio. O projeto perde o car\u00e1ter conclusivo se houver decis\u00e3o divergente entre as comiss\u00f5es ou se, independentemente de ser aprovado ou rejeitado, houver recurso assinado por 52 deputados para a aprecia\u00e7\u00e3o da mat\u00e9ria no Plen\u00e1rio.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">car\u00e1ter conclusivo<\/span> e ser\u00e1 analisada agora pela Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania. Para virar lei, precisa ser aprovada pela C\u00e2mara e pelo Senado.<\/p>\n<p><a href=\"https:\/\/www.camara.leg.br\/noticias\/573454-SAIBA-MAIS-SOBRE-A-TRAMITACAO-DE-PROJETOS-DE-LEI\">Saiba mais sobre a tramita\u00e7\u00e3o de projetos de lei<\/a><\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Reportagem \u2013 Emanuelle Brasil<br \/>Edi\u00e7\u00e3o \u2013 Pierre Triboli<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1284020-comissao-aprova-projeto-que-autoriza-extensao-de-estagio-apos-conclusao-de-curso-superior\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>19\/06\/2026 &#8211; 16:25 \u00a0 Kayo Magalh\u00e3es\/C\u00e2mara dos Deputados Luiz Carlos Motta, relator do projeto de lei A Comiss\u00e3o de Educa\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9695"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=9695"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/9696"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=9695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=9695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=9695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}