{"id":9656,"date":"2026-06-18T16:21:30","date_gmt":"2026-06-18T19:21:30","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/comissao-avalia-politicas-publicas-de-acolhimento-e-protecao-social-de-maes-atipicas-noticias\/"},"modified":"2026-06-18T16:21:30","modified_gmt":"2026-06-18T19:21:30","slug":"comissao-avalia-politicas-publicas-de-acolhimento-e-protecao-social-de-maes-atipicas-noticias","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/comissao-avalia-politicas-publicas-de-acolhimento-e-protecao-social-de-maes-atipicas-noticias\/","title":{"rendered":"Comiss\u00e3o avalia pol\u00edticas p\u00fablicas de acolhimento e prote\u00e7\u00e3o social de m\u00e3es at\u00edpicas &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<div>\n<p class=\"g-artigo__data-hora\">\n\t\t\t\t\t\t\t\t\t\t\t18\/06\/2026 &#8211; 11:16 \u00a0\n\t\t\t\t\t\t\t\t\t\t<\/p>\n<div id=\"image-container-1283557\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1283557\">\n<p><em>Depositphotos<\/em><\/p>\n<p>Responsabilidade pelo cuidado recai quase exclusivamente sobre as m\u00e3es<\/p>\n<\/p><\/div>\n<p>A Comiss\u00e3o de Defesa dos Direitos da Mulher da C\u00e2mara dos Deputados promove audi\u00eancia p\u00fablica nesta sexta-feira (19) sobre os desafios enfrentados pelas m\u00e3es at\u00edpicas.<\/p>\n<p>M\u00e3es at\u00edpicas cuidam de filhos com defici\u00eancia, transtornos do neurodesenvolvimento, doen\u00e7as raras e outras condi\u00e7\u00f5es que exigem acompanhamento constante.<\/p>\n<p>O debate ser\u00e1 realizado \u00e0s 10 horas, no plen\u00e1rio 14.<\/p>\n<p>A audi\u00eancia atende a pedido da deputada <span data-placeholder-token=\"true\">Erika Kokay<\/span> (PT-DF).\u00a0Segundo ela, o objetivo \u00e9 discutir as condi\u00e7\u00f5es de vida dessas mulheres e avaliar pol\u00edticas p\u00fablicas de acolhimento, prote\u00e7\u00e3o social, sa\u00fade mental, inclus\u00e3o educacional e apoio \u00e0s fam\u00edlias.<\/p>\n<p><span data-placeholder-token=\"true\">Erika Kokay <\/span>afirma que, em muitos casos, as m\u00e3es assumem quase sozinhas os cuidados com os filhos. Isso pode afetar a sa\u00fade f\u00edsica e mental, a renda, o trabalho e a vida social dessas mulheres.<\/p>\n<p>\u201cA audi\u00eancia p\u00fablica tamb\u00e9m pretende dar visibilidade \u00e0s experi\u00eancias e viv\u00eancias dessas mulheres, contribuindo para a constru\u00e7\u00e3o de pol\u00edticas mais humanas, inclusivas e efetivas.\u201d<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Da Reda\u00e7\u00e3o &#8211; ND<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1283173-comissao-avalia-politicas-publicas-de-acolhimento-e-protecao-social-de-maes-atipicas\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>18\/06\/2026 &#8211; 11:16 \u00a0 Depositphotos Responsabilidade pelo cuidado recai quase exclusivamente sobre as m\u00e3es A Comiss\u00e3o de Defesa dos Direitos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9657,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9656"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=9656"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/9657"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=9656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=9656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=9656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}