{"id":9641,"date":"2026-06-18T02:32:58","date_gmt":"2026-06-18T05:32:58","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/comissao-mista-aprova-mp-do-frete-e-cria-piso-salarial-para-motorista-de-longa-distancia-noticias\/"},"modified":"2026-06-18T02:32:58","modified_gmt":"2026-06-18T05:32:58","slug":"comissao-mista-aprova-mp-do-frete-e-cria-piso-salarial-para-motorista-de-longa-distancia-noticias","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/comissao-mista-aprova-mp-do-frete-e-cria-piso-salarial-para-motorista-de-longa-distancia-noticias\/","title":{"rendered":"Comiss\u00e3o mista aprova MP do Frete e cria piso salarial para motorista de longa dist\u00e2ncia &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"g-artigo__data-hora\">\n\t\t\t\t\t\t\t\t\t\t\t17\/06\/2026 &#8211; 19:33 \u00a0<br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<span>\u2022 \u00a0 Atualizado em 17\/06\/2026 &#8211; 20:41<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/p>\n<div id=\"image-container-1283395\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1283395\">\n<p><em>Waldemir Barreto\/Ag\u00eancia Senado<\/em><\/p>\n<p>Deputado Z\u00e9 Trov\u00e3o, relator da medida provis\u00f3ria<\/p>\n<\/p><\/div>\n<p>A comiss\u00e3o mista que analisa a Medida Provis\u00f3ria 1343\/26 aprovou nesta quarta-feira (17) o parecer do deputado Z\u00e9 Trov\u00e3o (PL-SC). Al\u00e9m de refor\u00e7ar os mecanismos de fiscaliza\u00e7\u00e3o do piso m\u00ednimo do frete rodovi\u00e1rio, o texto aprovado institui um piso salarial nacional para motoristas de longa dist\u00e2ncia. A MP foi em seguida aprovada pelo Plen\u00e1rio da C\u00e2mara e seguir\u00e1 para vota\u00e7\u00e3o no Senado.<\/p>\n<p><strong>Fiscaliza\u00e7\u00e3o<\/strong><br \/>Em vigor desde mar\u00e7o, a MP 1346\/26 foi editada pela Presid\u00eancia da Rep\u00fablica para fortalecer a fiscaliza\u00e7\u00e3o da Pol\u00edtica Nacional de Pisos M\u00ednimos do Transporte Rodovi\u00e1rio de Cargas.<\/p>\n<p>Para isso, torna obrigat\u00f3rio o registro de todas as opera\u00e7\u00f5es por meio do C\u00f3digo Identificador da Opera\u00e7\u00e3o de Transporte (Ciot), que re\u00fane informa\u00e7\u00f5es sobre contratante, transportador, origem e destino da carga e valor do frete.<\/p>\n<p>O respectivo sistema deve impedir a emiss\u00e3o do c\u00f3digo quando a contrata\u00e7\u00e3o registrar valor inferior ao piso m\u00ednimo definido pela Ag\u00eancia Nacional de Transportes Terrestres (ANTT).<\/p>\n<p><strong>Parecer<\/strong><br \/>O parecer aprovado pela comiss\u00e3o mista mant\u00e9m a estrutura da medida provis\u00f3ria, mas promove altera\u00e7\u00f5es.<\/p>\n<p>Uma das altera\u00e7\u00f5es \u00e9 a que modifica a Lei 13.103\/15, que regulamenta a profiss\u00e3o de motorista. A mudan\u00e7a prev\u00ea:<\/p>\n<ul>\n<li>piso salarial nacional de R$ 5 mil mensais para motoristas empregados no transporte rodovi\u00e1rio de cargas de longa dist\u00e2ncia;<\/li>\n<li>amplia\u00e7\u00e3o das a\u00e7\u00f5es apoiadas pelo Programa de Apoio ao Desenvolvimento do Transporte de Cargas Nacional (Procargas), incluindo renova\u00e7\u00e3o e moderniza\u00e7\u00e3o da frota, implanta\u00e7\u00e3o de pontos de parada e descanso, qualifica\u00e7\u00e3o profissional, inova\u00e7\u00e3o tecnol\u00f3gica, seguran\u00e7a vi\u00e1ria e melhoria das condi\u00e7\u00f5es de trabalho;<\/li>\n<li>cria\u00e7\u00e3o, no \u00e2mbito do Procargas, da Pol\u00edtica Nacional Permanente de Renova\u00e7\u00e3o da Frota de Ve\u00edculos de Transporte Rodovi\u00e1rio de Cargas (PNPR-Cargas); e<\/li>\n<li>prioridade para transportadores aut\u00f4nomos de cargas (TACs) e cooperativas de transporte de cargas no acesso a a\u00e7\u00f5es, financiamentos, incentivos e programas vinculados ao Procargas.<\/li>\n<\/ul>\n<p>Entre as demais mudan\u00e7as, o parecer detalha a metodologia que dever\u00e1 ser utilizada pela ANTT para calcular os pisos m\u00ednimos de frete, al\u00e9m de determinar a publica\u00e7\u00e3o semestral das planilhas e das mem\u00f3rias de c\u00e1lculo.<\/p>\n<p>O texto tamb\u00e9m amplia as regras relacionadas ao Ciot, que passa a registrar informa\u00e7\u00f5es sobre a forma e o prazo de pagamento do frete.<\/p>\n<p><strong>Frete adiantado<\/strong><br \/>O texto aprovado assegura aos transportadores aut\u00f4nomos de cargas o adiantamento de pelo menos 70% do valor do frete no momento da contrata\u00e7\u00e3o, com pagamento do saldo em at\u00e9 tr\u00eas dias \u00fateis ap\u00f3s a entrega da carga.<\/p>\n<p>A comiss\u00e3o mista respons\u00e1vel pela an\u00e1lise da MP 1346\/26 foi instalada em 9 de junho \u2014 e nessa mesma data foram eleitos o vice-presidente, o relator e o relator-revisor do grupo. O presidente da comiss\u00e3o, senador Carlos F\u00e1varo (PSD-MT), foi eleito nesta quarta-feira.<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Da Reda\u00e7\u00e3o \u2013 AC<br \/>Com informa\u00e7\u00f5es da Ag\u00eancia Senado<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1283385-comissao-mista-aprova-mp-do-frete-e-cria-piso-salarial-para-motorista-de-longa-distancia\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>17\/06\/2026 &#8211; 19:33 \u00a0 \u2022 \u00a0 Atualizado em 17\/06\/2026 &#8211; 20:41 Waldemir Barreto\/Ag\u00eancia Senado Deputado Z\u00e9 Trov\u00e3o, relator da medida [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9642,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9641"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=9641"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/9642"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=9641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=9641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=9641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}