{"id":9631,"date":"2026-06-17T21:39:04","date_gmt":"2026-06-18T00:39:04","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/saiba-mais-sobre-as-novas-regras-aprovadas-pela-camara-para-protecao-da-industria-brasileira-noticias\/"},"modified":"2026-06-17T21:39:04","modified_gmt":"2026-06-18T00:39:04","slug":"saiba-mais-sobre-as-novas-regras-aprovadas-pela-camara-para-protecao-da-industria-brasileira-noticias","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/saiba-mais-sobre-as-novas-regras-aprovadas-pela-camara-para-protecao-da-industria-brasileira-noticias\/","title":{"rendered":"Saiba mais sobre as novas regras aprovadas pela C\u00e2mara para prote\u00e7\u00e3o da ind\u00fastria brasileira &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"g-artigo__data-hora\">\n\t\t\t\t\t\t\t\t\t\t\t17\/06\/2026 &#8211; 20:26 \u00a0\n\t\t\t\t\t\t\t\t\t\t<\/p>\n<div id=\"image-container-1283418\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1283418\">\n<p><em>Thiago Cristino\/C\u00e2mara dos Deputados<\/em><\/p>\n<p>Deputados votaram o projeto na sess\u00e3o do Plen\u00e1rio desta quarta-feira<\/p>\n<\/p><\/div>\n<p>O texto aprovado pela C\u00e2mara dos Deputados para o Projeto de Lei 4133\/23 define novas regras para prote\u00e7\u00e3o da ind\u00fastria nacional.<\/p>\n<p>Confira pontos da proposta:<\/p>\n<p><strong>Briga comercial<\/strong><br \/>O <span id=\"4098\" class=\"termoGlossario\" title=\"Nome que se d\u00e1 ao texto que altera substancialmente o conte\u00fado original da proposta. O substitutivo \u00e9 apresentado pelo relator e tem prefer\u00eancia na vota\u00e7\u00e3o sobre o projeto original.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">substitutivo<\/span> do relator do projeto, deputado Rodrigo Rollemberg (PSB-DF), procura dar mais poderes ao governo para proteger a ind\u00fastria nacional de importa\u00e7\u00f5es que possam comprometer a competitividade.<\/p>\n<p>Quanto a bens importados investigados por fraudes e inconsist\u00eancias em rela\u00e7\u00e3o \u00e0s condi\u00e7\u00f5es comerciais declaradas, o substitutivo determina a aplica\u00e7\u00e3o do chamado licenciamento n\u00e3o autom\u00e1tico.<\/p>\n<p>Esse tipo de licenciamento tem prazo maior para ser concedido ao importador (60 dias) e \u00e9 utilizado frequentemente quando o produto depende de an\u00e1lise de outros \u00f3rg\u00e3os, como Anvisa, Minist\u00e9rio da Agricultura e Ibama.<\/p>\n<p>No \u00e2mbito do Sistema Brasileiro de Com\u00e9rcio de Emiss\u00f5es de Gases de Efeito Estufa (SBCE), o governo poder\u00e1 estabelecer um mecanismo de ajuste de carbono nas fronteiras a fim de anular os custos econ\u00f4micos das importa\u00e7\u00f5es que aumentem a quantidade de carbono equivalente na matriz produtiva brasileira.<\/p>\n<p>O mecanismo j\u00e1 \u00e9 utilizado, por exemplo, pela Uni\u00e3o Europeia, que aplica sobre produtos intensivos em carbono que entram no bloco um valor l\u00edquido equivalente ao que as empresas locais pagariam se emitissem aqueles gases na Europa.<\/p>\n<p>Sobre os investimentos diretos, o Poder Executivo poder\u00e1, com base em an\u00e1lise de risco fundamentada e na forma do regulamento, pedir informa\u00e7\u00f5es adicionais, monitorar e impor condicionalidades a investimentos estrangeiros diretos no Brasil.<\/p>\n<p>A inten\u00e7\u00e3o \u00e9 evitar amea\u00e7a \u00e0 seguran\u00e7a nacional, \u00e0 ordem p\u00fablica, a setores estrat\u00e9gicos da economia ou aos objetivos estrat\u00e9gicos da pol\u00edtica industrial.<\/p>\n<p><strong>Contramedidas<\/strong><br \/>Na Lei de Contramedidas aprovada no ano passado (<a class=\"linkLegislacao\" href=\"https:\/\/www2.camara.gov.br\/legin\/fed\/lei\/2025\/lei-15122-11-abril-2025-797315-norma-pl.html\" target=\"_blank\" rel=\"noopener noreferrer\">Lei 15.122\/25<\/a>) para fazer frente a consequ\u00eancias derivadas do aumento unilateral de tarifas pelo governo Trump (EUA), o texto aprovado prev\u00ea a ado\u00e7\u00e3o de outros tipos de medidas sem necessidade de coordena\u00e7\u00e3o com o setor privado prevista em lei.<\/p>\n<p>Assim, poder\u00e3o ser adotadas medidas, de forma isolada ou cumulativa, relativas a:<\/p>\n<ul>\n<li>regras comerciais, regulat\u00f3rias, financeiras, tribut\u00e1rias ou patrimoniais;<\/li>\n<li>explora\u00e7\u00e3o econ\u00f4mica de ativos, acesso ao mercado nacional e fluxo transfronteiri\u00e7o de capitais;<\/li>\n<li>acesso a contrata\u00e7\u00f5es p\u00fablicas, a regimes de concess\u00e3o, permiss\u00e3o ou autoriza\u00e7\u00e3o; e<\/li>\n<li>acesso a programas, instrumentos ou benef\u00edcios de pol\u00edtica p\u00fablica, tais como subs\u00eddios, subven\u00e7\u00f5es, financiamentos, garantias ou incentivos de qualquer natureza.<\/li>\n<\/ul>\n<p><strong>Automa\u00e7\u00e3o<\/strong><br \/>O projeto permite licita\u00e7\u00e3o restrita a bens e servi\u00e7os com tecnologia desenvolvida no pa\u00eds de acordo com o Processo Produtivo B\u00e1sico (PPB) para implanta\u00e7\u00e3o, manuten\u00e7\u00e3o e aperfei\u00e7oamento de sistemas de tecnologia da informa\u00e7\u00e3o e comunica\u00e7\u00e3o.<\/p>\n<p>No caso de empate na contrata\u00e7\u00e3o desses bens e servi\u00e7os, haver\u00e1 prefer\u00eancia para aqueles resultantes de desenvolvimento e inova\u00e7\u00e3o tecnol\u00f3gica no Brasil. O empate ser\u00e1 considerado quando a proposta apresentada por benefici\u00e1rio da prefer\u00eancia for at\u00e9 10% superior \u00e0 proposta mais bem classificada.<\/p>\n<p>Para exercer a prefer\u00eancia, no entanto, a empresa dever\u00e1 seguir o pre\u00e7o da empresa preterida ou baix\u00e1-lo.<\/p>\n<p><strong>Metas<\/strong><br \/>Os objetivos e metas poder\u00e3o ser definidos por setor estrat\u00e9gico ou por \u201cmiss\u00f5es\u201d relacionadas a desafios sociais, ambientais, econ\u00f4micos e tecnol\u00f3gicos relevantes para o pa\u00eds.<\/p>\n<p>Se o formato escolhido for dessas miss\u00f5es, elas devem visar a cadeias produtivas ou nichos espec\u00edficos, para os quais os instrumentos de execu\u00e7\u00e3o precisam ser explicitamente identificados, com as metas e indicadores de desempenho. As escolhas ter\u00e3o de sair depois de di\u00e1logo sistem\u00e1tico e permanente com o setor privado industrial.<\/p>\n<p>Os objetivos e metas dever\u00e3o ser formulados utilizando indicadores quantitativos e qualitativos, como:<\/p>\n<ul>\n<li>n\u00edveis de produ\u00e7\u00e3o desejados ou necess\u00e1rios;<\/li>\n<li>conte\u00fado local e agrega\u00e7\u00e3o de valor;<\/li>\n<li>empregos criados;<\/li>\n<li>sal\u00e1rios, qualidade das ocupa\u00e7\u00f5es e melhoria do mercado de trabalho;<\/li>\n<li>redu\u00e7\u00e3o de desigualdades regionais e sociais;<\/li>\n<li>redu\u00e7\u00e3o das emiss\u00f5es de gases de efeito estufa e par\u00e2metros de economia circular; e<\/li>\n<li>autonomia produtiva e tecnol\u00f3gica e redu\u00e7\u00e3o da depend\u00eancia externa.<\/li>\n<\/ul>\n<p><strong>Instrumentos<\/strong><br \/>O texto define v\u00e1rios instrumentos a serem explicitados na pol\u00edtica industrial para se alcan\u00e7ar os objetivos e metas. O governo poder\u00e1 atuar, por exemplo, na regula\u00e7\u00e3o econ\u00f4mica setorial, com previs\u00e3o de investimentos, contrata\u00e7\u00f5es e concess\u00f5es p\u00fablicas com \u00edndices de conte\u00fado nacional m\u00ednimo, exclusividade ou margem de prefer\u00eancia para empresas nacionais, tratamento priorit\u00e1rio ou exclusivo para cooperativas e empresas brasileiras de capital nacional.<\/p>\n<p>Outro m\u00e9todo ser\u00e1 a utiliza\u00e7\u00e3o de empresas estatais e suas participa\u00e7\u00f5es em empreendimentos privados, inclusive por meio de participa\u00e7\u00f5es acion\u00e1rias.<\/p>\n<p>Instrumentos tradicionais tamb\u00e9m est\u00e3o previstos, como subven\u00e7\u00f5es e incentivos para investimento e pesquisa, cr\u00e9ditos e financiamentos p\u00fablicos em condi\u00e7\u00f5es favorecidas.<\/p>\n<p>O plano poder\u00e1 contemplar ainda est\u00edmulos a empresas brasileiras de capital nacional e contrapartidas a investimentos estrangeiros por meio de joint-ventures, transfer\u00eancia de tecnologias e de conhecimentos produtivos e capacita\u00e7\u00e3o de fornecedores.<\/p>\n<p>Sob pena de n\u00e3o poderem acessar qualquer desses benef\u00edcios por 1 a 3 anos, as empresas diretamente contempladas ser\u00e3o obrigadas a cumprir contrapartidas e apresentar anualmente demonstrativos financeiros, al\u00e9m de ceder dados para a elabora\u00e7\u00e3o de relat\u00f3rio anual pelo Executivo.<\/p>\n<p><strong>Revis\u00e3o<\/strong><br \/>Se o descumprimento das contrapartidas e obriga\u00e7\u00f5es ocorrer por causa de fatos relevantes futuros e alheios ao controle da empresa, o Poder Executivo poder\u00e1 revisar ou reprogramar essas contrapartidas ou adequar metas e prazos.<\/p>\n<p>Isso ser\u00e1 poss\u00edvel ainda se os fatos se relacionarem a riscos tecnol\u00f3gicos ou restri\u00e7\u00f5es \u00e0 concorr\u00eancia.<\/p>\n<p><strong>Economia do carbono<\/strong><br \/>O texto aprovado pela C\u00e2mara determina que a pol\u00edtica industrial e tecnol\u00f3gica seja articulada com a estrat\u00e9gia de descarboniza\u00e7\u00e3o e de transi\u00e7\u00e3o energ\u00e9tica, inclusive com incentivo a energias renov\u00e1veis.<\/p>\n<p>No entanto, por outro lado, tamb\u00e9m estabelece que a pol\u00edtica industrial dever\u00e1 promover a ind\u00fastria de refino de petr\u00f3leo e fortalecer a cadeia nacional de fornecedores de bens e servi\u00e7os para a ind\u00fastria de petr\u00f3leo e g\u00e1s, como a ind\u00fastria naval.<\/p>\n<p><strong>Relat\u00f3rio anual<\/strong><br \/>A cada dois anos, o Poder Executivo dever\u00e1 publicar relat\u00f3rio sobre a pol\u00edtica industrial, com avalia\u00e7\u00e3o dos resultados e dados sobre:<\/p>\n<ul>\n<li>o cumprimento dos objetivos e metas e a evolu\u00e7\u00e3o dos seus respectivos indicadores;<\/li>\n<li>cada plano, pol\u00edtica ou programa com o cumprimento dos objetivos e metas;<\/li>\n<li>registros de propriedade intelectual;<\/li>\n<li>o fomento e o desenvolvimento da economia verde, da descarboniza\u00e7\u00e3o dos setores produtivos no pa\u00eds e da bioeconomia;<\/li>\n<li>a transforma\u00e7\u00e3o digital do parque industrial brasileiro; e<\/li>\n<li>a evolu\u00e7\u00e3o da balan\u00e7a comercial dos setores industriais estrat\u00e9gicos, com destaque para exporta\u00e7\u00f5es de bens de maior complexidade e valor agregado.<\/li>\n<\/ul>\n<p>Na avalia\u00e7\u00e3o da evolu\u00e7\u00e3o dos indicadores de metas e objetivos, ser\u00e3o consideradas as altera\u00e7\u00f5es no ambiente macroecon\u00f4mico e de outros fatores com impacto que estejam fora da al\u00e7ada das inst\u00e2ncias e \u00f3rg\u00e3os respons\u00e1veis pela pol\u00edtica industrial.<\/p>\n<p><strong>Carreiras p\u00fablicas<\/strong><br \/>O texto aprovado tamb\u00e9m condiciona a condu\u00e7\u00e3o da pol\u00edtica industrial \u00e0 adequada dota\u00e7\u00e3o or\u00e7ament\u00e1ria e de recursos humanos e meios administrativos necess\u00e1rios.<\/p>\n<p>Isso inclui a realiza\u00e7\u00e3o de concursos p\u00fablicos, a valoriza\u00e7\u00e3o e o provimento regular de carreiras estrat\u00e9gicas e a estrutura\u00e7\u00e3o permanente dos \u00f3rg\u00e3os e unidades respons\u00e1veis pela formula\u00e7\u00e3o, execu\u00e7\u00e3o, monitoramento e avalia\u00e7\u00e3o da pol\u00edtica.<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Reportagem \u2013 Eduardo Piovesan<br \/>Edi\u00e7\u00e3o \u2013 Pierre Triboli<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1283403-saiba-mais-sobre-as-novas-regras-aprovadas-pela-camara-para-protecao-da-industria-brasileira\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>17\/06\/2026 &#8211; 20:26 \u00a0 Thiago Cristino\/C\u00e2mara dos Deputados Deputados votaram o projeto na sess\u00e3o do Plen\u00e1rio desta quarta-feira O texto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9632,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[34],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9631"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=9631"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9631\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/9632"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=9631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=9631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=9631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}