{"id":9619,"date":"2026-06-17T18:57:14","date_gmt":"2026-06-17T21:57:14","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/especialistas-afirmam-que-processo-de-desertificacao-do-semiarido-e-reversivel-noticias\/"},"modified":"2026-06-17T18:57:14","modified_gmt":"2026-06-17T21:57:14","slug":"especialistas-afirmam-que-processo-de-desertificacao-do-semiarido-e-reversivel-noticias","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/especialistas-afirmam-que-processo-de-desertificacao-do-semiarido-e-reversivel-noticias\/","title":{"rendered":"Especialistas afirmam que processo de desertifica\u00e7\u00e3o do semi\u00e1rido \u00e9 revers\u00edvel &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"g-artigo__data-hora\">\n\t\t\t\t\t\t\t\t\t\t\t17\/06\/2026 &#8211; 17:52 \u00a0\n\t\t\t\t\t\t\t\t\t\t<\/p>\n<div id=\"image-container-1283243\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1283243\">\n<p><em>Kayo Magalh\u00e3es \/ C\u00e2mara dos Deputados<\/em><\/p>\n<p>Semin\u00e1rio foi promovido pelo Cedes e pela Frente Parlamentar Ambientalista<\/p>\n<\/p><\/div>\n<p>Especialistas ouvidos em semin\u00e1rio na C\u00e2mara dos Deputados nesta quarta-feira (17) afirmaram que o processo de desertifica\u00e7\u00e3o do semi\u00e1rido brasileiro \u00e9 revers\u00edvel. O evento foi organizado pelo Centro de Estudos e Debates Estrat\u00e9gicos da C\u00e2mara, em parceria com a Secretaria de Ci\u00eancia e Tecnologia para o Desenvolvimento Social, do Minist\u00e9rio da Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o, e com a Frente Parlamentar Ambientalista da C\u00e2mara.<\/p>\n<p>Jos\u00e9 Etham Barbosa, diretor do Instituto Nacional do Semi\u00e1rido (Insa), explicou que a institui\u00e7\u00e3o atua h\u00e1 22 anos com os moradores da regi\u00e3o por meio de tecnologias criadas para combater a desertifica\u00e7\u00e3o com a produ\u00e7\u00e3o de alimentos. A tecnologia envolve o uso de energias renov\u00e1veis para uma melhor conviv\u00eancia com a seca. Barbosa afirmou que o processo de desertifica\u00e7\u00e3o n\u00e3o \u00e9 insol\u00favel, mas alertou para a seriedade do problema.<\/p>\n<p>\u201cA desertifica\u00e7\u00e3o n\u00e3o \u00e9 um fato em si, como os desertos naturais, por exemplo. N\u00f3s estamos em terras profundas que est\u00e3o se degradando ao longo do tempo com caracter\u00edsticas de desertifica\u00e7\u00e3o. Falamos de um problema n\u00e3o s\u00f3 ambiental, mas que afeta a vida, a seguran\u00e7a alimentar e o futuro de milh\u00f5es de pessoas\u201d, disse.<\/p>\n<p>De acordo com Barbosa, a \u00e1rea de risco de desertifica\u00e7\u00e3o expandiu entre 2000 e 2020 e hoje chega a mais de 170 mil km2, onde vivem cerca de 39 milh\u00f5es de pessoas. Ele admitiu que o abastecimento de \u00e1gua evoluiu nas \u00faltimas d\u00e9cadas, mas ressaltou que o mesmo n\u00e3o aconteceu com o saneamento. Barbosa explicou o funcionamento de um sistema chamado Sara, de saneamento e de tratamento de \u00e1gua, inaugurado em 2017, cuja tecnologia foi desenvolvida na tentativa de resolver problemas como escassez h\u00eddrica e esgotamento sanit\u00e1rio.<\/p>\n<p>&#8220;O grande diferencial do Sara \u00e9 que ele transforma um problema ambiental em ativo produtivo: enquanto trata o esgoto dom\u00e9stico, reduz a contamina\u00e7\u00e3o ambiental, reaproveita \u00e1gua e nutrientes e fortalece a produ\u00e7\u00e3o agr\u00edcola familiar&#8221;, disse.<\/p>\n<p>Al\u00e9m do Sara, j\u00e1 consolidado, o Insa est\u00e1 testando outro sistema de saneamento e re\u00faso, chamado Siriema. O instituto \u00e9 ligado ao Minist\u00e9rio da Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o, que atua em parceria com a Embrapa e governos estaduais para o combate ao problema.<\/p>\n<p><strong>Outros projetos<\/strong><br \/>O representante do Instituto de Pesquisa para o Desenvolvimento (IRD) no Brasil, Abdelfetah Siffedine, afirmou que h\u00e1 v\u00e1rios projetos sobre o assunto na regi\u00e3o Nordeste, como o que envolve a universidade federal e a Funda\u00e7\u00e3o Cearense de Meteorologia e Recursos H\u00eddricos (Funceme).<\/p>\n<p>\u201cNo Cear\u00e1, com a Funceme, estamos trabalhando em duas frentes: uma ligada \u00e0 \u00e1gua e outra ligada \u00e0 recupera\u00e7\u00e3o das terras degradadas. Nas terras degradadas, a gente viu modelos formando pequenos agricultores. Com esses modelos de recupera\u00e7\u00e3o da terra, a biomassa cresceu duas vezes. Com a biomassa crescendo, h\u00e1 uma economia que tem uma consequ\u00eancia direta, como a economia de mel, e os modelos est\u00e3o crescendo porque esses agricultores est\u00e3o formando outros agricultores\u201d, explicou.<\/p>\n<p>Na regi\u00e3o tamb\u00e9m est\u00e1 sendo feita a hidrologia espacial, que \u00e9 o estudo do ciclo da \u00e1gua e dos recursos h\u00eddricos por meio de sat\u00e9lites. Sensores medem o n\u00edvel dos rios e a qualidade da \u00e1gua, segundo explicou o representante da ag\u00eancia da ONU para a Alimenta\u00e7\u00e3o e a Agricultura (FAO) no Brasil, Gustavo Kauark Chianca.<\/p>\n<p>O uso coletivo da terra (chamado &#8220;fundo de pasto&#8221;) e o manejo sustent\u00e1vel da Caatinga por meio da cria\u00e7\u00e3o de animais soltos e do extrativismo garantem o acesso a alimentos e a gera\u00e7\u00e3o de renda, com o bioma preservado.<\/p>\n<p>\u201cUma das tecnologias importantes \u00e9 o fundo de pasto na regi\u00e3o do semi\u00e1rido brasileiro, feito por agricultores familiares. \u00c9 um manejo hoje reconhecido e que garante a seguran\u00e7a alimentar, a sustentabilidade e ajuda a combater a desertifica\u00e7\u00e3o\u201d, salientou.<\/p>\n<p><strong>Recursos<\/strong><br \/>O deputado In\u00e1cio Arruda (PCdoB-CE), que integra a Comiss\u00e3o de Ci\u00eancia e Tecnologia da C\u00e2mara, apontou que, no Brasil, o combate \u00e0 desertifica\u00e7\u00e3o \u00e9 feito por duas inst\u00e2ncias: os governos estaduais atuam com a ajuda da Embrapa Caprinos e Ovinos, com sede em Sobral (CE), que trabalha com o desenvolvimento sustent\u00e1vel na cria\u00e7\u00e3o desses rebanhos num estado com 11% do territ\u00f3rio em processo de desertifica\u00e7\u00e3o; j\u00e1 a Embrapa Semi\u00e1rido pesquisa a produ\u00e7\u00e3o sustent\u00e1vel na regi\u00e3o e tem sede em Petrolina (PE). Mas ele ressaltou que nada disso \u00e9 vi\u00e1vel sem recursos.<\/p>\n<p>\u201cSomos n\u00f3s que decidimos, no final, se vai ter recurso ou n\u00e3o para que essas pol\u00edticas sejam executadas. N\u00f3s cuidamos do Or\u00e7amento, ent\u00e3o, estamos buscando examinar onde a gente coloca exatamente os recursos necess\u00e1rios para combater a desertifica\u00e7\u00e3o no nosso pa\u00eds\u201d, disse ele.<\/p>\n<p>O Brasil vai participar em agosto da COP 17, a Confer\u00eancia das Partes da Conven\u00e7\u00e3o das Na\u00e7\u00f5es Unidas de Combate \u00e0 Desertifica\u00e7\u00e3o (UNCCD), na Mong\u00f3lia. O evento vai discutir as metas de restaura\u00e7\u00e3o de terras globais, o combate \u00e0 seca e \u00e0 desertifica\u00e7\u00e3o e a prote\u00e7\u00e3o de pastagens.<\/p>\n<p>O Semin\u00e1rio Internacional de Combate \u00e0 Desertifica\u00e7\u00e3o: desafios cient\u00edficos e tecnol\u00f3gicos para o Semi\u00e1rido reuniu na C\u00e2mara dos Deputados representantes do poder p\u00fablico, pesquisadores, organismos internacionais, universidades, movimentos sociais e especialistas da \u00e1rea ambiental, clim\u00e1tica, cient\u00edfica e tecnol\u00f3gica.<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Da Reda\u00e7\u00e3o \u2013 AC<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1283159-especialistas-afirmam-que-processo-de-desertificacao-do-semiarido-e-reversivel\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>17\/06\/2026 &#8211; 17:52 \u00a0 Kayo Magalh\u00e3es \/ C\u00e2mara dos Deputados Semin\u00e1rio foi promovido pelo Cedes e pela Frente Parlamentar Ambientalista [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9619"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=9619"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/9620"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=9619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=9619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=9619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}