{"id":10867,"date":"2026-08-13T18:53:13","date_gmt":"2026-08-13T21:53:13","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/medida-provisoria-abre-credito-orcamentario-para-aumento-de-estoques-de-alimentos-por-causa-do-el-nino\/"},"modified":"2026-08-13T18:53:13","modified_gmt":"2026-08-13T21:53:13","slug":"medida-provisoria-abre-credito-orcamentario-para-aumento-de-estoques-de-alimentos-por-causa-do-el-nino","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/medida-provisoria-abre-credito-orcamentario-para-aumento-de-estoques-de-alimentos-por-causa-do-el-nino\/","title":{"rendered":"Medida provis\u00f3ria abre cr\u00e9dito or\u00e7ament\u00e1rio para aumento de estoques de alimentos por causa do El Ni\u00f1o"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<figure class=\"materia__midia\" style=\"float: none; margin: 24px 0px;\" data-midia=\"820200\"><img decoding=\"async\" src=\"https:\/\/www.camara.leg.br\/midias\/image\/2021\/10\/img20210331115251179-768x512.jpeg\" alt=\"Agropecu\u00e1ria - planta\u00e7\u00f5es - colheita de arroz - MST come\u00e7a a colheita de 12,4 mil toneladas de arroz\"\/><figcaption><span class=\"materia__legenda-imagem\">Uma das medidas previstas pelo governo \u00e9 adquirir estoques de arroz<\/span> &#8211; <span class=\"materia__creditos-imagem\" style=\"color:#5f5f5e\">Foto: Tiago Giannichini\/FotosP\u00fablicas<\/span><\/figcaption><\/figure>\n<p>O Congresso Nacional analisa Medida Provis\u00f3ria (MP) 1384\/26, que abre cr\u00e9dito extraordin\u00e1rio de R$ 925 milh\u00f5es no Or\u00e7amento de 2026 para combater de maneira preventiva os efeitos do El Ni\u00f1o para o per\u00edodo 2026\/2027.<\/p>\n<p>Segundo o governo, s\u00e3o a\u00e7\u00f5es de abastecimento e seguran\u00e7a alimentar e nutricional diante dos riscos associados aos eventos clim\u00e1ticos extremos previstos com a chegada do fen\u00f4meno, que consiste no aquecimento das \u00e1guas do oceano Pac\u00edfico na regi\u00e3o equatorial. As a\u00e7\u00f5es s\u00e3o as seguintes:<\/p>\n<ul>\n<li>aquisi\u00e7\u00e3o de estoques de arroz e de milho;<\/li>\n<li>custos operacionais de manuten\u00e7\u00e3o de estoques;<\/li>\n<li>aquisi\u00e7\u00e3o e distribui\u00e7\u00e3o de alimentos a grupos populacionais tradicionais e a fam\u00edlias em situa\u00e7\u00e3o de inseguran\u00e7a alimentar advindas de situa\u00e7\u00f5es de emerg\u00eancia ou calamidade p\u00fablica; e<\/li>\n<li>atendimento de fam\u00edlias afetadas por enchentes, inunda\u00e7\u00f5es e outros eventos hidrol\u00f3gicos extremos.<\/li>\n<\/ul>\n<p>A mensagem que acompanha a proposta afirma que a probabilidade de um El Ni\u00f1o muito forte passou para 81% em 9 de julho, uma eleva\u00e7\u00e3o de dezoito pontos percentuais em menos de um m\u00eas. \u201cN\u00e3o se sustenta, portanto, a obje\u00e7\u00e3o de que se trata de despesa previs\u00edvel n\u00e3o consignada na lei or\u00e7ament\u00e1ria. O que era previs\u00edvel em 2025 era a neutralidade\u201d, diz a mensagem.<\/p>\n<p>A Companhia Nacional de Abastecimento (Conab) informou que o volume proposto de arroz somado ao estoque atual representa incremento de cerca de 106%. O estoque total vai corresponder a aproximadamente 5,4% da produ\u00e7\u00e3o nacional de arroz da safra 2025\/26 ou cerca de 20 dias de consumo nacional.<\/p>\n<p>No caso do milho, a demanda adicional \u00e9 justamente a estimada para o per\u00edodo em que se est\u00e1 prevendo seca no Nordeste, quando regularmente haveria chuva.<\/p>\n<p>Em rela\u00e7\u00e3o aos eventos hidrol\u00f3gicos, o governo afirma que entre os dias 16 e 23 de julho, fortes chuvas no estado do Rio Grande do Sul atingiram 218 munic\u00edpios com quase 60 mil pessoas afetadas e que este seria apenas o come\u00e7o dos impactos esperados pelo El Ni\u00f1o na regi\u00e3o.<\/p>\n<p>A medida ser\u00e1 analisada pela <span id=\"4053\" class=\"termoGlossario materia__glossario\" title=\"Comiss\u00e3o de deputados e senadores respons\u00e1vel pela an\u00e1lise das propostas or\u00e7ament\u00e1rias elaboradas pelo Executivo: Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO), Lei Or\u00e7ament\u00e1ria Anual (LOA) e Plano Plurianual (PPA).\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\" style=\"color:#5f5f5e;border-bottom:none\">Comiss\u00e3o Mista de Or\u00e7amento<\/span> e, em seguida, pelos plen\u00e1rios da C\u00e2mara e do Senado.<\/p>\n<p><a href=\"https:\/\/www.camara.leg.br\/noticias\/573452-saiba-mais-sobre-a-tramitacao-de-mps\">Saiba mais sobre a tramita\u00e7\u00e3o de medidas provis\u00f3rias<\/a><\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1297542-medida-provisoria-abre-credito-orcamentario-para-aumento-de-estoques-de-alimentos-por-causa-do-el-nino\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma das medidas previstas pelo governo \u00e9 adquirir estoques de arroz &#8211; Foto: Tiago Giannichini\/FotosP\u00fablicas O Congresso Nacional analisa Medida [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10867"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=10867"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10867\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/6909"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=10867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=10867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=10867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}