{"id":10789,"date":"2026-08-10T13:48:31","date_gmt":"2026-08-10T16:48:31","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/projeto-torna-obrigatoria-a-instalacao-de-banheiros-neutros-em-locais-publicos-e-privados\/"},"modified":"2026-08-10T13:48:31","modified_gmt":"2026-08-10T16:48:31","slug":"projeto-torna-obrigatoria-a-instalacao-de-banheiros-neutros-em-locais-publicos-e-privados","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/projeto-torna-obrigatoria-a-instalacao-de-banheiros-neutros-em-locais-publicos-e-privados\/","title":{"rendered":"Projeto torna obrigat\u00f3ria a instala\u00e7\u00e3o de banheiros neutros em locais p\u00fablicos e privados"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<figure class=\"materia__midia\" style=\"float: none; margin: 24px 0px;\" data-midia=\"1296060\"><img decoding=\"async\" src=\"https:\/\/www.camara.leg.br\/midias\/image\/2026\/08\/depositphotos-717271536-xl-1-768x576.jpg\" alt=\"Placas de banheiro\"\/><figcaption><span class=\"materia__legenda-imagem\">Banheiros neutros constituir\u00e3o uma categoria independente<\/span> &#8211; <span class=\"materia__creditos-imagem\" style=\"color:#5f5f5e\">Foto: Depositphotos<\/span><\/figcaption><\/figure>\n<p>O Projeto de Lei 2117\/26 torna obrigat\u00f3ria a instala\u00e7\u00e3o de banheiros de uso neutro em estabelecimentos p\u00fablicos e privados de uso coletivo. A proposta prev\u00ea que essas instala\u00e7\u00f5es dever\u00e3o ser individuais, com porta de fechamento total para garantir a privacidade, e n\u00e3o ter\u00e3o restri\u00e7\u00e3o de g\u00eanero.<\/p>\n<p>Pelo texto em an\u00e1lise na C\u00e2mara dos Deputados, a regra dever\u00e1 valer para locais com circula\u00e7\u00e3o regular igual ou superior a 50 usu\u00e1rios por turno.<\/p>\n<p>A exig\u00eancia abranger\u00e1 \u00f3rg\u00e3os p\u00fablicos, shoppings com mais de 2 mil metros quadrados, universidades, aeroportos, hospitais, hot\u00e9is e arenas esportivas.<\/p>\n<p>Os locais que descumprirem a futura lei ser\u00e3o notificados e ter\u00e3o um prazo de 60 dias para se adequarem. Ap\u00f3s esse per\u00edodo, o infrator estar\u00e1 sujeito a uma multa mensal de R$ 5 mil e \u00e0 interdi\u00e7\u00e3o parcial da \u00e1rea sanit\u00e1ria.<\/p>\n<h3 class=\"ds-titulo-subsecao\">Categoria independente<\/h3>\n<p>\n                        Autor da proposta, o deputado Fernando Rodolfo (PRD-PE) disse que os banheiros neutros reduzir\u00e3o situa\u00e7\u00f5es de constrangimento e viol\u00eancia contra pessoas transg\u00eanero e n\u00e3o bin\u00e1rias em espa\u00e7os p\u00fablicos. Segundo ele, a medida preserva integralmente os banheiros masculinos e femininos tradicionais.<\/p>\n<p>\u201cA solu\u00e7\u00e3o adequada para acomodar a diversidade de identidades de g\u00eanero n\u00e3o \u00e9 a altera\u00e7\u00e3o dos sanit\u00e1rios masculinos ou femininos existentes, mas sim a cria\u00e7\u00e3o de uma terceira categoria de instala\u00e7\u00f5es sanit\u00e1rias\u201d, afirmou o deputado.<\/p>\n<p>Pela proposta, os banheiros neutros constituir\u00e3o uma categoria independente.\u00a0A instala\u00e7\u00e3o deles n\u00e3o poder\u00e1 substituir, reduzir ou comprometer a oferta dos sanit\u00e1rios masculinos, femininos e para pessoas com defici\u00eancia exigidos por lei.<\/p>\n<h3 class=\"ds-titulo-subsecao\">Pr\u00f3ximos passos<\/h3>\n<p>\n                        O projeto ser\u00e1 analisado em <span id=\"4322\" class=\"termoGlossario materia__glossario\" title=\"Rito de tramita\u00e7\u00e3o pelo qual o projeto \u00e9 votado apenas pelas comiss\u00f5es designadas para analis\u00e1-lo, dispensada a delibera\u00e7\u00e3o do Plen\u00e1rio. O projeto perde o car\u00e1ter conclusivo se houver decis\u00e3o divergente entre as comiss\u00f5es ou se, independentemente de ser aprovado ou rejeitado, houver recurso assinado por 52 deputados para a aprecia\u00e7\u00e3o da mat\u00e9ria no Plen\u00e1rio.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\" style=\"color:#5f5f5e;border-bottom:none\">car\u00e1ter conclusivo<\/span> pelas comiss\u00f5es de Desenvolvimento Urbano; de Direitos Humanos, Minorias e Igualdade Racial; de Finan\u00e7as e Tributa\u00e7\u00e3o; e de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania.<\/p>\n<p>Para virar lei, o texto ter\u00e1 de ser aprovado pela C\u00e2mara e pelo Senado.<\/p>\n<p><a href=\"https:\/\/www.camara.leg.br\/noticias\/573454-SAIBA-MAIS-SOBRE-A-TRAMITACAO-DE-PROJETOS-DE-LEI\">Saiba mais sobre a tramita\u00e7\u00e3o de projetos de lei<\/a><\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1295426-projeto-torna-obrigatoria-a-instalacao-de-banheiros-neutros-em-locais-publicos-e-privados\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Banheiros neutros constituir\u00e3o uma categoria independente &#8211; Foto: Depositphotos O Projeto de Lei 2117\/26 torna obrigat\u00f3ria a instala\u00e7\u00e3o de banheiros [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10789"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=10789"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/6909"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=10789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=10789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=10789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}