{"id":10759,"date":"2026-08-06T14:00:36","date_gmt":"2026-08-06T17:00:36","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/conselho-de-etica-analisa-processos-contra-quatro-deputados-na-terca-feira\/"},"modified":"2026-08-06T14:00:36","modified_gmt":"2026-08-06T17:00:36","slug":"conselho-de-etica-analisa-processos-contra-quatro-deputados-na-terca-feira","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/conselho-de-etica-analisa-processos-contra-quatro-deputados-na-terca-feira\/","title":{"rendered":"Conselho de \u00c9tica analisa processos contra quatro deputados na ter\u00e7a-feira"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<figure class=\"materia__midia\" style=\"float: none; margin: 24px 0px;\" data-midia=\"1295515\"><img decoding=\"async\" src=\"https:\/\/www.camara.leg.br\/midias\/image\/2026\/08\/img20260519154529914-768x473.jpg\" alt=\"Aprecia\u00e7\u00e3o de parecer. Dep. Ricardo Maia (MDB-BA). Dep. Fabio Schiochet (UNI\u00c3O-SC)\"\/><figcaption><span class=\"materia__legenda-imagem\">Conselho de \u00c9tica reunido<\/span> &#8211; <span class=\"materia__creditos-imagem\" style=\"color:#5f5f5e\">Foto: Kayo Magalh\u00e3es \/ C\u00e2mara dos Deputados<\/span><\/figcaption><\/figure>\n<p>O <span id=\"4203\" class=\"termoGlossario materia__glossario\" title=\"\u00d3rg\u00e3o encarregado de zelar pela observ\u00e2ncia da \u00e9tica e do decoro parlamentar na C\u00e2mara. Compete-lhe instaurar e instruir os processos disciplinares referentes a den\u00fancias de atos incompat\u00edveis com o decoro parlamentar, recomendando ou n\u00e3o puni\u00e7\u00f5es cab\u00edveis aos deputados, que v\u00e3o desde a censura oral at\u00e9 a perda de mandato. Caso recomende puni\u00e7\u00f5es severas, o parecer do conselho dever\u00e1 ser votado pelo Plen\u00e1rio em dois dias, em vota\u00e7\u00e3o secreta. O conselho atua mediante provoca\u00e7\u00e3o da Mesa Diretora, nos casos de instaura\u00e7\u00e3o de processo disciplinar.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\" style=\"color:#5f5f5e;border-bottom:none\">Conselho de \u00c9tica e Decoro Parlamentar<\/span> da C\u00e2mara dos Deputados realiza, na pr\u00f3xima ter\u00e7a-feira (11), duas reuni\u00f5es para analisar processos por suposta quebra de decoro.<\/p>\n<p>\u00c0s 11 horas, em local a ser definido, o colegiado apreciar\u00e1 pareceres preliminares apresentados a quatro representa\u00e7\u00f5es.<\/p>\n<p>\u00c0s 16 horas, no plen\u00e1rio 11, ser\u00e3o realizadas oitivas de testemunhas e de representados em dois processos envolvendo o deputado Andr\u00e9 Janones (Rede-MG).<\/p>\n<h3 class=\"ds-titulo-subsecao\">Erika Hilton<\/h3>\n<p>\n                        Na reuni\u00e3o da manh\u00e3, o conselho vai analisar o parecer do deputado Cabo Gilberto Silva (PL-PB) \u00e0 <a href=\"https:\/\/www.camara.leg.br\/proposicoesWeb\/prop_mostrarintegra?codteor=3115347&amp;filename=REP%208\/2026\">Representa\u00e7\u00e3o 8\/26<\/a>, de autoria do Miss\u00e3o contra a deputada Erika Hilton (PSOL-SP).<\/p>\n<p>O partido reclama de postagem de Erika Hilton nas redes sociais, que teria usado termos ofensivos, como &#8220;imbeCIS&#8221; e &#8220;esgoto da sociedade&#8221;, para criticar opositores pol\u00edticos.<\/p>\n<p>O Miss\u00e3o afirma que a mensagem \u00e9 ofensiva e discriminat\u00f3ria contra mulheres cisg\u00eanero (aquelas cuja identidade de g\u00eanero corresponde ao sexo biol\u00f3gico).<\/p>\n<h3 class=\"ds-titulo-subsecao\">Paulo Bilynskyj<\/h3>\n<p>O conselho tamb\u00e9m vai analisar o parecer do deputado Delegado Fabio Costa (PP-AL) \u00e0 <a href=\"https:\/\/www.camara.leg.br\/proposicoesWeb\/prop_mostrarintegra?codteor=3115224&amp;filename=REP%202\/2026\">Representa\u00e7\u00e3o 2\/26<\/a>, apresentada pelo Psol contra o deputado Delegado Paulo Bilynskyj (PL-SP).<\/p>\n<p>O partido reclama que, durante o per\u00edodo em que o parlamentar presidiu a Comiss\u00e3o de Seguran\u00e7a P\u00fablica da C\u00e2mara, ele desrespeitou a atua\u00e7\u00e3o dos deputados do Psol que compunham o colegiado.<\/p>\n<h3 class=\"ds-titulo-subsecao\">Rog\u00e9rio Correia<\/h3>\n<p>\n                        Por fim, o conselho vai analisar os pareceres do deputado Moses Rodrigues (Uni\u00e3o-CE) \u00e0s representa\u00e7\u00f5es <a href=\"https:\/\/www.camara.leg.br\/proposicoesWeb\/prop_mostrarintegra?codteor=3115242&amp;filename=REP%205\/2026\">5\/26<\/a> e <a href=\"https:\/\/www.camara.leg.br\/proposicoesWeb\/prop_mostrarintegra?codteor=3115251&amp;filename=REP%206\/2026\">6\/26<\/a>, ambas de autoria do PL contra o deputado Rog\u00e9rio Correia (PT-MG).<\/p>\n<p>O partido acusa Correia de publicar uma imagem manipulada por intelig\u00eancia artificial que simulava um encontro entre o ex-presidente Jair Bolsonaro e empres\u00e1rios do setor financeiro.<\/p>\n<p>Correia \u00e9 acusado ainda de agredir fisicamente os deputados Alfredo Gaspar (PL-AL) e Luiz Lima (Novo-RJ) durante a reuni\u00e3o da CPMI do INSS que aprovou a quebra de sigilo do empres\u00e1rio F\u00e1bio Lu\u00eds Lula da Silva, filho do presidente Lula.<\/p>\n<h3 class=\"ds-titulo-subsecao\">Andr\u00e9 Janones<\/h3>\n<p>\n                        \u00c0 tarde, o Conselho de \u00c9tica ouve testemunhas em dois processos contra o deputado Andr\u00e9 Janones.<\/p>\n<p>Na <a href=\"https:\/\/www.camara.leg.br\/proposicoesWeb\/prop_mostrarintegra?codteor=2975349&amp;filename=REP%208\/2025\">Representa\u00e7\u00e3o 8\/25<\/a>, ser\u00e3o ouvidas as testemunhas indicadas pela defesa: a vereadora Joelma da Silva Almeida, Suelaine Soares e Lucely Aparecida Costa, al\u00e9m do pr\u00f3prio deputado Andr\u00e9 Janones, caso confirmem presen\u00e7a.<\/p>\n<p>Nesse processo, o PL acusa Janones de ter solicitado a devolu\u00e7\u00e3o de parte do sal\u00e1rio de servidores para beneficiar sua campanha.<\/p>\n<p>Na <a href=\"https:\/\/www.camara.leg.br\/proposicoesWeb\/prop_mostrarintegra?codteor=2975439&amp;filename=REP%2014\/2025\">Representa\u00e7\u00e3o 14\/25<\/a>, est\u00e1 prevista a oitiva do deputado Gustavo Gayer (PL-GO), testemunha indicada pelo relator, deputado Fausto Jr. (Uni\u00e3o-AM) e do depoimento de Janones.<\/p>\n<p>Nesse processo, o PL acusa Janones de ter postado, em suas redes sociais, ofensas graves contra Gayer.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1295468-conselho-de-etica-analisa-processos-contra-quatro-deputados-na-terca-feira\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conselho de \u00c9tica reunido &#8211; Foto: Kayo Magalh\u00e3es \/ C\u00e2mara dos Deputados O Conselho de \u00c9tica e Decoro Parlamentar da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[27],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10759"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=10759"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/6909"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=10759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=10759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=10759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}