{"id":10727,"date":"2026-08-03T19:10:57","date_gmt":"2026-08-03T22:10:57","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/proposta-prioriza-atendimento-remoto-para-pessoas-com-deficiencia-com-dificuldade-de-locomocao\/"},"modified":"2026-08-03T19:10:57","modified_gmt":"2026-08-03T22:10:57","slug":"proposta-prioriza-atendimento-remoto-para-pessoas-com-deficiencia-com-dificuldade-de-locomocao","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/proposta-prioriza-atendimento-remoto-para-pessoas-com-deficiencia-com-dificuldade-de-locomocao\/","title":{"rendered":"Proposta prioriza atendimento remoto para pessoas com defici\u00eancia com dificuldade de locomo\u00e7\u00e3o"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<figure class=\"materia__midia\" style=\"float: none; margin: 24px 0px;\" data-midia=\"1294875\"><img decoding=\"async\" src=\"https:\/\/www.camara.leg.br\/midias\/image\/2026\/08\/img20260708121152652-768x473.jpg\" alt=\"Discuss\u00e3o e vota\u00e7\u00e3o de propostas legislativas. Dep. Helder Salom\u00e3o (PT - ES)\"\/><figcaption><span class=\"materia__legenda-imagem\">Helder Salom\u00e3o: inclus\u00e3o e autonomia por meio da tecnologia<\/span> &#8211; <span class=\"materia__creditos-imagem\" style=\"color:#5f5f5e\">Foto: Kayo Magalh\u00e3es \/ C\u00e2mara dos deputados<\/span><\/figcaption><\/figure>\n<p>O Projeto de Lei 1253\/26 pro\u00edbe \u00f3rg\u00e3os p\u00fablicos de exigirem, como regra, o comparecimento presencial de pessoas com defici\u00eancia quando o deslocamento representar um sacrif\u00edcio exagerado ou indevido. O texto altera o <a href=\"https:\/\/www2.camara.leg.br\/legin\/fed\/lei\/2015\/lei-13146-6-julho-2015-781174-publicacaooriginal-147468-pl.html\">Estatuto da Pessoa com Defici\u00eancia<\/a> para estabelecer que a administra\u00e7\u00e3o deve priorizar, nesses casos, o atendimento remoto via canais digitais ou telef\u00f4nicos acess\u00edveis.<\/p>\n<p>Pela proposta, o poder p\u00fablico deve garantir sites e aplicativos adaptados, al\u00e9m do uso de assinaturas eletr\u00f4nicas para validar documentos. Tamb\u00e9m ser\u00e1 proibida a exig\u00eancia de documentos que a administra\u00e7\u00e3o j\u00e1 possua em suas bases de dados, facilitando o compartilhamento de informa\u00e7\u00f5es entre os \u00f3rg\u00e3os e reduzindo a burocracia para o cidad\u00e3o.<\/p>\n<p>A exig\u00eancia de presen\u00e7a f\u00edsica passar\u00e1 a ser uma medida excepcional. Caso um \u00f3rg\u00e3o obrigue a ida presencial, a autoridade respons\u00e1vel dever\u00e1 justificar por escrito o motivo de o servi\u00e7o n\u00e3o ser realizado de forma remota. Se a tecnologia for insuficiente, o contato dever\u00e1 ser feito na resid\u00eancia da pessoa ou permitir que ela seja representada por um procurador.<\/p>\n<p>O projeto tamb\u00e9m assegura o atendimento domiciliar para per\u00edcias m\u00e9dicas e sociais do INSS, atendimentos de sa\u00fade pelo SUS (p\u00fablicos ou conveniados) e servi\u00e7os de assist\u00eancia social.<\/p>\n<p>&#8220;A proposta eleva a tecnologia ao papel de instrumento de inclus\u00e3o e autonomia, garantindo racionalidade e respeito \u00e0 dignidade humana&#8221;, justificou o autor da proposta, deputado Helder Salom\u00e3o (PT-ES).<\/p>\n<h3 class=\"ds-titulo-subsecao\">Pr\u00f3ximas etapas<\/h3>\n<p>A proposta ser\u00e1 analisada, em <span id=\"4322\" class=\"termoGlossario materia__glossario\" title=\"Rito de tramita\u00e7\u00e3o pelo qual o projeto \u00e9 votado apenas pelas comiss\u00f5es designadas para analis\u00e1-lo, dispensada a delibera\u00e7\u00e3o do Plen\u00e1rio. O projeto perde o car\u00e1ter conclusivo se houver decis\u00e3o divergente entre as comiss\u00f5es ou se, independentemente de ser aprovado ou rejeitado, houver recurso assinado por 52 deputados para a aprecia\u00e7\u00e3o da mat\u00e9ria no Plen\u00e1rio.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\" style=\"color:#5f5f5e;border-bottom:none\">car\u00e1ter conclusivo<\/span>, pelas comiss\u00f5es de Defesa dos Direitos das Pessoas com Defici\u00eancia; e de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania.<\/p>\n<p>Para virar lei, o texto deve ser aprovado pela C\u00e2mara e pelo Senado.<\/p>\n<p><a href=\"https:\/\/www.camara.leg.br\/noticias\/573454-SAIBA-MAIS-SOBRE-A-TRAMITACAO-DE-PROJETOS-DE-LEI\">Saiba mais sobre a tramita\u00e7\u00e3o de projetos de lei<\/a><\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1292549-proposta-prioriza-atendimento-remoto-para-pessoas-com-deficiencia-com-dificuldade-de-locomocao\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Helder Salom\u00e3o: inclus\u00e3o e autonomia por meio da tecnologia &#8211; Foto: Kayo Magalh\u00e3es \/ C\u00e2mara dos deputados O Projeto de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10727"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=10727"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10727\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/6909"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=10727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=10727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=10727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}