{"id":10726,"date":"2026-08-03T18:49:20","date_gmt":"2026-08-03T21:49:20","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/congresso-tem-32-medidas-provisorias-para-serem-votadas\/"},"modified":"2026-08-03T18:49:20","modified_gmt":"2026-08-03T21:49:20","slug":"congresso-tem-32-medidas-provisorias-para-serem-votadas","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/congresso-tem-32-medidas-provisorias-para-serem-votadas\/","title":{"rendered":"Congresso tem 32 medidas provis\u00f3rias para serem votadas"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<figure class=\"materia__midia\" style=\"float: none; margin: 24px 0px;\" data-midia=\"1291154\"><img decoding=\"async\" src=\"https:\/\/www.camara.leg.br\/midias\/image\/2026\/07\/img20210705103924466-768x513.jpg\" alt=\"Energia - combust\u00edvel - bomba de combust\u00edvel - gasolina - posto de combust\u00edvel - Governo da Bahia mant\u00e9m mesma al\u00edquota de cobran\u00e7a de ICMS sobre pre\u00e7o de combust\u00edveis h\u00e1 quatro anos\"\/><figcaption><span class=\"materia__legenda-imagem\">Algumas das MPs tratam sobre combust\u00edveis<\/span> &#8211; <span class=\"materia__creditos-imagem\" style=\"color:#5f5f5e\">Foto: Carol Garcia\/GOVBA<\/span><\/figcaption><\/figure>\n<p>O Congresso Nacional retoma os trabalhos em agosto com 32 medidas provis\u00f3rias para analisar. Entre elas est\u00e3o propostas sobre renegocia\u00e7\u00e3o de d\u00edvidas, combust\u00edveis, transporte, ressarcimento de descontos indevidos em benef\u00edcios do INSS e apoio a empresas afetadas pelo aumento das tarifas impostas pelos Estados Unidos.<\/p>\n<p>Tamb\u00e9m h\u00e1 uma s\u00e9rie de medidas editadas para subsidiar combust\u00edveis, reduzindo os impactos da alta internacional do petr\u00f3leo, e outras de apoio a empresas afetadas pelos tarifa\u00e7os dos Estados Unidos.<\/p>\n<p>V\u00e1rias MPs trazem incentivos e linhas de cr\u00e9dito para o transporte de passageiros, com programas focados na renova\u00e7\u00e3o sustent\u00e1vel de frotas para motoristas profissionais e taxistas, al\u00e9m de apoio ao setor a\u00e9reo.<\/p>\n<p>As medidas produzem efeitos imediatos, mas dependem da aprova\u00e7\u00e3o do Congresso para serem convertidas em lei. A vota\u00e7\u00e3o ocorre primeiro nas comiss\u00f5es mistas, depois na C\u00e2mara e, por \u00faltimo, no Senado. Caso n\u00e3o sejam aprovadas no prazo m\u00e1ximo de 120 dias, as MPs perdem a validade. A contagem dos prazos \u00e9 interrompida durante o recesso parlamentar, o que n\u00e3o aconteceu em 2026 porque o Congresso n\u00e3o p\u00f4de entrar formalmente em recesso sem a vota\u00e7\u00e3o do projeto da Lei de Diretrizes Or\u00e7ament\u00e1rias.<\/p>\n<p>O projeto da LDO de 2027 (<a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1263876-projeto-do-governo-preve-salario-minimo-de-r-1-717-em-2027-e-define-metas-fiscais\">PLN 2\/26<\/a>) ainda n\u00e3o foi votado.<\/p>\n<p><a href=\"https:\/\/www.camara.leg.br\/noticias\/573452-saiba-mais-sobre-a-tramitacao-de-mps\">Conhe\u00e7a a tramita\u00e7\u00e3o de medidas provis\u00f3rias<\/a><\/p>\n<h3 class=\"ds-titulo-subsecao\">Desenrola<\/h3>\n<p>No Novo Desenrola Brasil, institu\u00eddo pela <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1286298-trabalhadores-informais-em-dia-com-as-dividas-podem-renegocia-las-com-bancos\">MP 1355\/26<\/a>, pessoas com renda mensal de at\u00e9 R$ 8.105 poder\u00e3o refinanciar d\u00edvidas de at\u00e9 R$ 15 mil por banco com taxa de juros m\u00e1xima de 1,99% ao m\u00eas. A MP tamb\u00e9m cont\u00e9m regras espec\u00edficas para aliviar d\u00edvidas de pequenas e microempresas, alcan\u00e7ando ainda os endividados com o Fundo de Financiamento Estudantil (Fies).<\/p>\n<p>O programa atinge as d\u00edvidas relativas a empr\u00e9stimos feitos at\u00e9 31 de janeiro de 2026, com parcelas atrasadas entre 91 e 720 dias. Essas d\u00edvidas devem ser pessoais e relativas a cart\u00e3o de cr\u00e9dito parcelado ou rotativo, cheque especial e cr\u00e9dito pessoal sem consigna\u00e7\u00e3o em folha, por exemplo.<\/p>\n<p>Editada em maio, a medida precisa ser votada at\u00e9 31 de agosto e ainda aguarda a instala\u00e7\u00e3o da comiss\u00e3o mista na qual ser\u00e1 analisada, para seguir para a C\u00e2mara e depois para o Senado.<\/p>\n<p>Tamb\u00e9m aguarda instala\u00e7\u00e3o da comiss\u00e3o mista a \u00a0<a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1271806-mp-1357-26-governo-do-brasil-publica-mp-que-zera-imposto-da-chamada-taxa-das-blusinhas\">MP 1373\/26<\/a>, que institui os programas Desenrola Adimplentes e Fies Empreendedor. As novas regras permitem a renegocia\u00e7\u00e3o de d\u00edvidas de trabalhadores informais que estejam com o pagamento das parcelas em dia.<\/p>\n<p>J\u00e1 os estudantes beneficiados pelo Fies que estiverem com as parcelas em dia poder\u00e3o ter acesso a um cr\u00e9dito especial para investir em seu pr\u00f3prio neg\u00f3cio.<\/p>\n<h3 class=\"ds-titulo-subsecao\">Taxa das blusinhas<\/h3>\n<p>Publicada em maio, a <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1293191-medida-provisoria-abre-credito-orcamentario-para-complementar-ressarcimento-de-descontos-indevidos-em-beneficios-do-inss\">MP 1357\/26<\/a>\u00a0tornou mais baratas as compras internacionais de pequeno valor. Um dos principais impactos pr\u00e1ticos da medida \u00e9 o fim do Imposto de Importa\u00e7\u00e3o para compras de at\u00e9 US$ 50 feitas por pessoas f\u00edsicas no \u00e2mbito do Programa Remessa Conforme. O tributo ficou popularmente conhecido como taxa das blusinhas.<\/p>\n<p>A cobran\u00e7a sobre compras internacionais de pequeno valor havia sido implementada em 2024 e gerou rea\u00e7\u00e3o de consumidores e debates entre plataformas estrangeiras de com\u00e9rcio eletr\u00f4nico e representantes do varejo nacional.<\/p>\n<h3 class=\"ds-titulo-subsecao\">INSS<\/h3>\n<p>Publicada em julho, a <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1283992-mp-amplia-atuacao-de-programa-para-reduzir-fila-do-inss\">MP 1378\/26<\/a>, abriu cr\u00e9dito extraordin\u00e1rio de R$ 547 milh\u00f5es ao Minist\u00e9rio da Previd\u00eancia Social. O dinheiro deve ser usado para ressarcir aposentados e pensionistas que sofreram descontos indevidos de entidades associativas. O ressarcimento possibilitado com esse cr\u00e9dito ser\u00e1 para quem se cadastrou no aplicativo Meu INSS at\u00e9 o dia 20 de junho.<\/p>\n<p>J\u00e1 a <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1272369-nova-medida-provisoria-enfrenta-alta-nos-precos-dos-combustiveis\">MP 1369\/26<\/a> amplia as atribui\u00e7\u00f5es do Programa de Gerenciamento de Benef\u00edcios (PGB). A inten\u00e7\u00e3o \u00e9 reduzir as filas de an\u00e1lise de benef\u00edcios do INSS e da Per\u00edcia M\u00e9dica Federal.<\/p>\n<h3 class=\"ds-titulo-subsecao\">Combust\u00edveis<\/h3>\n<p>A alta do petr\u00f3leo fez com que o governo editasse, no primeiro semestre de 2026, v\u00e1rias medidas provis\u00f3rias para tentar reduzir o impacto no pre\u00e7o dos combust\u00edveis para os brasileiros.<\/p>\n<p>Uma delas \u00e9 a <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1267779-mp-1351-26-mp-libera-r-330-milhoes-para-subsidiar-desconto-no-gas-de-cozinha\">MP 1349\/26<\/a>, que institui o Regime Emergencial de Abastecimento Interno de Combust\u00edveis. A medida ainda n\u00e3o foi analisada pela comiss\u00e3o mista e precisa ser votada ainda na primeira semana de agosto, j\u00e1 que o prazo se encerra no dia 4.<\/p>\n<p>Al\u00e9m dela, est\u00e3o em an\u00e1lise a <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1283974-medida-provisoria-abre-credito-orcamentario-de-r-8-bilhoes-para-financiamento-de-companhias-aereas\">MP 1358\/26<\/a>, que concede subven\u00e7\u00e3o econ\u00f4mica \u00e0 venda de combust\u00edveis derivados de petr\u00f3leo; a <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1286359-medida-provisoria-abre-credito-orcamentario-de-r-550-milhoes-para-subvencao-do-oleo-diesel\">MP 1363\/26<\/a>, com subs\u00eddio para produtores e importadores de diesel; e medidas com cr\u00e9ditos extraordin\u00e1rios para viabilizar a\u00e7\u00f5es contra a alta de pre\u00e7os de combust\u00edveis (<a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1293668-medida-provisoria-abre-credito-orcamentario-de-r-333-bilhoes-para-subsidios-a-importacao-de-combustiveis\">MP 1351\/26<\/a>, <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1294651-mp-1-379-2026-apos-novo-tarifaco-dos-eua-medida-provisoria-abre-linha-de-credito-extra\">MP 1368\/26<\/a>, <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1268490-mp-destina-recursos-orcamentarios-de-r-5-bilhoes-para-credito-as-exportacoes\">MP 1372\/26<\/a> e <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1274260-mp-1360-26-medida-provisoria-simplifica-regras-para-atividade-de-mototaxistas\">MP 1380\/26<\/a>)<\/p>\n<h3 class=\"ds-titulo-subsecao\">Tarifa\u00e7o<\/h3>\n<p>A <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1274263-mp-1359-26-medida-provisoria-libera-financiamento-para-motoristas-de-aplicativo-e-taxistas\">MP 1379\/26<\/a> viabiliza a terceira rodada do Plano Brasil Soberano, com um socorro de R$ 18,5 bilh\u00f5es em linhas de cr\u00e9dito com juros subsidiados para exportadores e setores considerados estrat\u00e9gicos para a economia nacional.<\/p>\n<p>Al\u00e9m das empresas diretamente atingidas pelo tarifa\u00e7o norte-americano, o programa passa a contemplar exportadores prejudicados por conflitos internacionais, como os do Golfo P\u00e9rsico. Tamb\u00e9m passam a ser contemplados setores considerados estrat\u00e9gicos.<\/p>\n<p>J\u00e1 a <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1282139-congresso-avalia-mp-que-cria-linha-de-credito-para-motociclista-de-aplicativo\">MP 1352\/26<\/a> destinou R$ 5 bilh\u00f5es adicionais para o Fundo de Garantia \u00e0 Exporta\u00e7\u00e3o (FGE), tamb\u00e9m para refor\u00e7ar o Plano Brasil Soberano.<\/p>\n<h3 class=\"ds-titulo-subsecao\">Transporte<\/h3>\n<p>Sete medidas em an\u00e1lise no Congresso tratam do setor de transporte de cargas e passageiros. Entre elas est\u00e1 a <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1269624-medida-oferece-r-145-bilhoes-para-financiar-compra-de-caminhoes-e-onibus\">MP 1360\/26<\/a>, que simplifica exig\u00eancias para o exerc\u00edcio da atividade dos mototaxistas, motoboys e profissionais de motofrete. O texto dispensa o registro do ve\u00edculo na categoria aluguel e a inspe\u00e7\u00e3o semestral dos equipamentos obrigat\u00f3rios e de seguran\u00e7a, entre outras regras.<\/p>\n<p>Outras medidas criam linhas de financiamento para a compra de ve\u00edculos novos por motoristas de aplicativo, taxistas e cooperativas de t\u00e1xi (<a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1284759-mp-faz-ajuste-em-programa-de-credito-para-micro-e-pequenas-empresas\">MP 1359\/26<\/a>), por mototaxistas e motoboys (<a href=\"https:\/\/www.camara.leg.br\/noticias\/1282139-MEDIDA-PROVISORIA-CRIA-FINANCIAMENTO-PARA-ENTREGADORES-COMPRAREM-MOTOS-E-BICICLETAS-ELETRICAS\">MP 1366\/26<\/a>) e por transportadores de cargas e empresas de transporte de cargas ou passageiros (<a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1279600-medida-provisoria-abre-credito-de-r-1-bilhao-para-setor-aereo-no-orcamento-de-2026\">MP 1353\/26<\/a>).<\/p>\n<p>Tamb\u00e9m h\u00e1 medidas provis\u00f3rias com cr\u00e9ditos extraordin\u00e1rios para viabilizar as linhas de financiamento de novos ve\u00edculos (<a href=\"https:\/\/www.camara.leg.br\/noticias\/1276497-MP-ABRE-CREDITO-DE-R%24-30-BI-PARA-FINANCIAR-COMPRA-DE-CARROS-POR-TAXISTAS-E-MOTORISTAS-DE-APLICATIVOS\">MP 1362\/26<\/a> e <a href=\"https:\/\/www.camara.leg.br\/noticias\/1268510-MP-ABRE-CREDITO-DE-R%24-17-BILHOES-PARA-RENOVAR-FROTA-DE-TRANSPORTE-E-APOIAR-EXPORTACOES\">MP 1354\/26<\/a>) e uma com cr\u00e9dito para empr\u00e9stimos \u00e0s companhias a\u00e9reas nacionais (<a href=\"https:\/\/www.camara.leg.br\/noticias\/1279600-MEDIDA-PROVISORIA-ABRE-CREDITO-DE-R%24-1-BILHAO-PARA-SETOR-AEREO-NO-ORCAMENTO-DE-2026\">MP 1365\/26<\/a>).<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1294621-congresso-tem-32-medidas-provisorias-para-serem-votadas\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Algumas das MPs tratam sobre combust\u00edveis &#8211; Foto: Carol Garcia\/GOVBA O Congresso Nacional retoma os trabalhos em agosto com 32 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[34],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10726"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=10726"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/6909"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=10726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=10726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=10726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}