{"id":10702,"date":"2026-07-30T17:28:29","date_gmt":"2026-07-30T20:28:29","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/projeto-libera-pesca-artesanal-em-unidades-de-conservacao-de-uso-sustentavel\/"},"modified":"2026-07-30T17:28:29","modified_gmt":"2026-07-30T20:28:29","slug":"projeto-libera-pesca-artesanal-em-unidades-de-conservacao-de-uso-sustentavel","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/projeto-libera-pesca-artesanal-em-unidades-de-conservacao-de-uso-sustentavel\/","title":{"rendered":"Projeto libera pesca artesanal em unidades de conserva\u00e7\u00e3o de uso sustent\u00e1vel"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<figure class=\"materia__midia\" style=\"float: none; margin: 24px 0px;\" data-midia=\"1294432\"><img decoding=\"async\" src=\"https:\/\/www.camara.leg.br\/midias\/image\/2026\/07\/img20250709114650557-2-768x473.jpg\" alt=\"Audi\u00eancia P\u00fablica - A Divis\u00e3o da Frequ\u00eancia de 6GHZ Entre o Wi-Fi e a Telefonia M\u00f3vel. Dep. AJ Albuquerque (PP - CE)\"\/><figcaption><span class=\"materia__legenda-imagem\">AJ Albuquerque: proposta visa compatibilizar a conserva\u00e7\u00e3o ambiental com a justi\u00e7a social<\/span> &#8211; <span class=\"materia__creditos-imagem\" style=\"color:#5f5f5e\">Foto: Kayo Magalh\u00e3es \/ C\u00e2mara dos Deputados<\/span><\/figcaption><\/figure>\n<p>O Projeto de Lei 436\/26 permite a pesca artesanal em unidades de conserva\u00e7\u00e3o de uso sustent\u00e1vel, exceto nas Reservas Particulares do Patrim\u00f4nio Natural. Pelo texto, a atividade dever\u00e1 seguir as regras do plano de manejo de cada local.<\/p>\n<p>Para trabalhar nessas \u00e1reas, o pescador precisar\u00e1 ter registro ativo no Minist\u00e9rio da Pesca e Aquicultura e comprovar resid\u00eancia ininterrupta por pelo menos cinco anos em munic\u00edpio vizinho \u00e0 unidade ou dentro dela.<\/p>\n<h3 class=\"ds-titulo-subsecao\">Justificativa<\/h3>\n<p>\n                        \u201cEsta proposta visa a compatibilizar a conserva\u00e7\u00e3o ambiental com a justi\u00e7a social e o reconhecimento dos direitos das comunidades tradicionais\u201d, disse o deputado AJ Albuquerque (PP-CE), na justificativa que acompanha o texto.<\/p>\n<p>\u201cA experi\u00eancia das reservas extrativistas demonstra que \u00e9 plenamente poss\u00edvel conciliar conserva\u00e7\u00e3o da biodiversidade com o uso sustent\u00e1vel dos recursos por popula\u00e7\u00f5es tradicionais\u201d, continuou o autor da proposta.<\/p>\n<h3 class=\"ds-titulo-subsecao\">Regras<\/h3>\n<p>\n                        O pescador artesanal dever\u00e1 fazer um cadastro no \u00f3rg\u00e3o gestor da unidade para obter autoriza\u00e7\u00e3o individual e intransfer\u00edvel. O plano de manejo definir\u00e1 o limite m\u00e1ximo de pescadores e a cota anual de captura, ouvida a comunidade.<\/p>\n<p>A proposta altera a <a class=\"linkLegislacao\" href=\"https:\/\/www2.camara.gov.br\/legin\/fed\/lei\/2000\/lei-9985-18-julho-2000-359708-norma-pl.html\" target=\"_blank\" rel=\"noopener noreferrer\">Lei 9.985\/00<\/a>, que trata do Sistema Nacional de Unidades de Conserva\u00e7\u00e3o da Natureza. Pelo texto, o exerc\u00edcio da atividade n\u00e3o gerar\u00e1 direito adquirido e poder\u00e1 ser revisto periodicamente. J\u00e1 as autoriza\u00e7\u00f5es poder\u00e3o ser suspensas ou canceladas se o trabalhador descumprir as normas ambientais.<\/p>\n<h3 class=\"ds-titulo-subsecao\">Pr\u00f3ximos passos<\/h3>\n<p>\n                        O projeto ser\u00e1 analisado em <span id=\"4322\" class=\"termoGlossario materia__glossario\" title=\"Rito de tramita\u00e7\u00e3o pelo qual o projeto \u00e9 votado apenas pelas comiss\u00f5es designadas para analis\u00e1-lo, dispensada a delibera\u00e7\u00e3o do Plen\u00e1rio. O projeto perde o car\u00e1ter conclusivo se houver decis\u00e3o divergente entre as comiss\u00f5es ou se, independentemente de ser aprovado ou rejeitado, houver recurso assinado por 52 deputados para a aprecia\u00e7\u00e3o da mat\u00e9ria no Plen\u00e1rio.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\" style=\"color:#5f5f5e;border-bottom:none\">car\u00e1ter conclusivo<\/span> pelas comiss\u00f5es de Agricultura, Pecu\u00e1ria, Abastecimento e Desenvolvimento Rural; de Meio Ambiente e Desenvolvimento Sustent\u00e1vel; e de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania.<\/p>\n<p>Para virar lei, o texto precisa ser aprovado pela C\u00e2mara e pelo Senado.<\/p>\n<p><a href=\"https:\/\/www.camara.leg.br\/noticias\/573454-SAIBA-MAIS-SOBRE-A-TRAMITACAO-DE-PROJETOS-DE-LEI\">Saiba mais sobre a tramita\u00e7\u00e3o de projetos de lei<\/a><\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1294396-projeto-libera-pesca-artesanal-em-unidades-de-conservacao-de-uso-sustentavel\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AJ Albuquerque: proposta visa compatibilizar a conserva\u00e7\u00e3o ambiental com a justi\u00e7a social &#8211; Foto: Kayo Magalh\u00e3es \/ C\u00e2mara dos Deputados [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10702"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=10702"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10702\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/6909"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=10702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=10702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=10702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}