{"id":10629,"date":"2026-07-24T20:55:58","date_gmt":"2026-07-24T23:55:58","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/projeto-permite-coletar-depoimento-de-testemunha-em-cartorio\/"},"modified":"2026-07-24T20:55:58","modified_gmt":"2026-07-24T23:55:58","slug":"projeto-permite-coletar-depoimento-de-testemunha-em-cartorio","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/projeto-permite-coletar-depoimento-de-testemunha-em-cartorio\/","title":{"rendered":"Projeto permite coletar depoimento de testemunha em cart\u00f3rio"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<figure class=\"materia__midia\" style=\"float: none; margin: 24px 0px;\" data-midia=\"1257467\"><img decoding=\"async\" src=\"https:\/\/www.camara.leg.br\/midias\/image\/2026\/03\/img20260317233306327-1-768x473.jpg\" alt=\"Deputado S\u00e9rgio Santos Rodrigues fala ao microfone\"\/><figcaption><span class=\"materia__legenda-imagem\">O autor da proposta, deputado S\u00e9rgio Santos Rodrigues<\/span> &#8211; <span class=\"materia__creditos-imagem\" style=\"color:#5f5f5e\">Foto: Kayo Magalh\u00e3es \/ C\u00e2mara dos Deputados<\/span><\/figcaption><\/figure>\n<p>O Projeto de Lei 143\/26, do deputado S\u00e9rgio Santos Rodrigues (Pode-MG), permite que testemunhas prestem depoimento em cart\u00f3rio, em vez de ir \u00e0 audi\u00eancia judicial. A medida vale para processos sobre direitos dispon\u00edveis, como quest\u00f5es de propriedade e contratos.<\/p>\n<p>O texto, em an\u00e1lise na C\u00e2mara dos Deputados, altera o <a href=\"https:\/\/www2.camara.leg.br\/legin\/fed\/lei\/2015\/lei-13105-16-marco-2015-780273-norma-pl.html\">C\u00f3digo de Processo Civil<\/a>.<\/p>\n<p>Pela proposta, as partes podem combinar de coletar os depoimentos em cart\u00f3rio, pagando os custos do servi\u00e7o. O tabeli\u00e3o ou pessoa autorizada por ele far\u00e1 a coleta.<\/p>\n<p>A ata produzida valer\u00e1 como prova em processos judiciais ou administrativos.<\/p>\n<h3 class=\"ds-titulo-subsecao\">Avalia\u00e7\u00e3o do juiz<\/h3>\n<p>\n                        O juiz poder\u00e1 aceitar a ata como prova e dispensar a audi\u00eancia se o documento for suficiente para esclarecer os pontos em discuss\u00e3o. Mas o magistrado continua com poder para avaliar a prova. Se achar necess\u00e1rio, poder\u00e1 chamar as testemunhas para novo depoimento em audi\u00eancia.<\/p>\n<h3 class=\"ds-titulo-subsecao\">Como funcionar\u00e1<\/h3>\n<p>\n                        O depoimento ser\u00e1 feito no cart\u00f3rio da cidade onde tramita o processo. Se a testemunha morar em outra cidade, poder\u00e1 ir ao cart\u00f3rio mais pr\u00f3ximo de sua casa.<\/p>\n<p>Todo o depoimento ser\u00e1 gravado em \u00e1udio e v\u00eddeo. As grava\u00e7\u00f5es ficar\u00e3o dispon\u00edveis para as partes e para o juiz.<\/p>\n<p>O projeto tamb\u00e9m permite que o cart\u00f3rio fa\u00e7a a coleta por videoconfer\u00eancia, seguindo as regras do Conselho Nacional de Justi\u00e7a.<\/p>\n<p>As partes dever\u00e3o avisar o juiz sobre o acordo feito, informar quais testemunhas ser\u00e3o ouvidas e qual cart\u00f3rio far\u00e1 o servi\u00e7o.<\/p>\n<p>O advogado, por sua vez, dever\u00e1 avisar a testemunha sobre o dia, a hora e o local do depoimento com pelo menos cinco dias de anteced\u00eancia.<\/p>\n<p>Se a testemunha faltar sem justificativa, o ato ser\u00e1 remarcado. O respons\u00e1vel pela aus\u00eancia da testemunha pagar\u00e1 os custos da remarca\u00e7\u00e3o.<\/p>\n<p>O depoimento ser\u00e1 p\u00fablico, exceto em processos que correm em segredo de justi\u00e7a.<\/p>\n<h3 class=\"ds-titulo-subsecao\">Solu\u00e7\u00f5es mais r\u00e1pidas<\/h3>\n<p>\n                        Para Rodrigues, a proposta estimula solu\u00e7\u00f5es mais r\u00e1pidas. &#8220;A escolha do tabeli\u00e3o de notas como agente respons\u00e1vel pela colheita do depoimento assegura imparcialidade, f\u00e9 p\u00fablica e seguran\u00e7a jur\u00eddica ao ato.&#8221;<\/p>\n<p>Rodrigues destacou que o projeto n\u00e3o retira poder do juiz, apenas oferece uma alternativa. Segundo ele, a iniciativa ajuda a reduzir a quantidade de audi\u00eancias e a tornar os processos mais r\u00e1pidos, sem prejudicar o direito de defesa das partes.<\/p>\n<h3 class=\"ds-titulo-subsecao\">Pr\u00f3ximos passos<\/h3>\n<p>\n                        A proposta ser\u00e1 analisada, em <span id=\"4322\" class=\"termoGlossario materia__glossario\" title=\"Rito de tramita\u00e7\u00e3o pelo qual o projeto \u00e9 votado apenas pelas comiss\u00f5es designadas para analis\u00e1-lo, dispensada a delibera\u00e7\u00e3o do Plen\u00e1rio. O projeto perde o car\u00e1ter conclusivo se houver decis\u00e3o divergente entre as comiss\u00f5es ou se, independentemente de ser aprovado ou rejeitado, houver recurso assinado por 52 deputados para a aprecia\u00e7\u00e3o da mat\u00e9ria no Plen\u00e1rio.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\" style=\"color:#5f5f5e;border-bottom:none\">car\u00e1ter conclusivo<\/span>, pela Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania. Para virar lei, precisa ser aprovada por C\u00e2mara e Senado.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1260094-projeto-permite-coletar-depoimento-de-testemunha-em-cartorio\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O autor da proposta, deputado S\u00e9rgio Santos Rodrigues &#8211; Foto: Kayo Magalh\u00e3es \/ C\u00e2mara dos Deputados O Projeto de Lei [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10629"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=10629"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10629\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/6909"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=10629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=10629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=10629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}