{"id":10592,"date":"2026-07-24T13:11:09","date_gmt":"2026-07-24T16:11:09","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/retrospectiva-camara-aprovou-acordo-mercosul-uniao-europeia-e-novas-regras-para-exportacoes\/"},"modified":"2026-07-24T13:11:09","modified_gmt":"2026-07-24T16:11:09","slug":"retrospectiva-camara-aprovou-acordo-mercosul-uniao-europeia-e-novas-regras-para-exportacoes","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/retrospectiva-camara-aprovou-acordo-mercosul-uniao-europeia-e-novas-regras-para-exportacoes\/","title":{"rendered":"Retrospectiva: C\u00e2mara aprovou acordo Mercosul\u2013Uni\u00e3o Europeia e novas regras para exporta\u00e7\u00f5es"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<figure class=\"materia__midia\" style=\"float: none; margin: 24px 0px;\" data-midia=\"1246922\"><img decoding=\"async\" src=\"https:\/\/www.camara.leg.br\/midias\/image\/2026\/02\/img20190703102214514-768x466.jpg\" alt=\"Acordo entre Mercosul e Uni\u00e3o Europeia\"\/><figcaption><span class=\"materia__legenda-imagem\">Acordo ficou em negocia\u00e7\u00e3o por d\u00e9cadas no Congresso<\/span> &#8211; <span class=\"materia__creditos-imagem\" style=\"color:#5f5f5e\">Foto: Reprodu\u00e7\u00e3o<\/span><\/figcaption><\/figure>\n<p>No primeiro semestre de 2026, o destaque da \u00e1rea de economia foi a aprova\u00e7\u00e3o do acordo entre o <span id=\"4265\" class=\"termoGlossario materia__glossario\" title=\"Bloco econ\u00f4mico formado por Argentina, Brasil, Paraguai e Uruguai, com o objetivo de criar um mercado comum com livre circula\u00e7\u00e3o de bens e servi\u00e7os, adotar uma pol\u00edtica externa comum e harmonizar legisla\u00e7\u00f5es nacionais, tendo em vista uma maior integra\u00e7\u00e3o. A Bol\u00edvia est\u00e1 em processo de ades\u00e3o ao bloco. J\u00e1 a Venezuela era membro pleno e est\u00e1 suspensa desde dezembro de 2016. Chile, Peru, Col\u00f4mbia e Equador s\u00e3o pa\u00edses associados, que podem participar como convidados de reuni\u00f5es do bloco, mas sem direito a voto.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\" style=\"color:#5f5f5e;border-bottom:none\">Mercosul<\/span> e a Uni\u00e3o Europeia, com previs\u00e3o de redu\u00e7\u00e3o de tarifas de importa\u00e7\u00e3o para diversos setores.<\/p>\n<p>No total, foram aprovados, pelo Plen\u00e1rio, 118 projetos de lei, 9 projetos de lei complementar, 20 medidas provis\u00f3rias, 12 projetos de decreto legislativo, 5 projetos de resolu\u00e7\u00e3o e 4 propostas de emenda \u00e0 Constitui\u00e7\u00e3o.<\/p>\n<h3 class=\"ds-titulo-subsecao\">Acordo Mercosul<\/h3>\n<p>Depois de d\u00e9cadas de negocia\u00e7\u00f5es, a C\u00e2mara dos Deputados aprovou o acordo provis\u00f3rio de com\u00e9rcio entre o Mercosul e a Uni\u00e3o Europeia. O texto prev\u00ea redu\u00e7\u00e3o de tarifas de importa\u00e7\u00e3o para diversos setores, com cronograma de desonera\u00e7\u00e3o de at\u00e9 18 anos para alguns produtos.<\/p>\n<p>O acordo foi aprovado por meio do <a href=\"https:\/\/www.camara.leg.br\/noticias\/1247799-CAMARA-APROVA-ACORDO-DE-COMERCIO-ENTRE-MERCOSUL-E-UNIAO-EUROPEIA\">Projeto de Decreto Legislativo (PDL) 41\/26<\/a> e publicado como <a href=\"https:\/\/www2.camara.leg.br\/legin\/fed\/decleg\/2026\/decretolegislativo-14-17-marco-2026-798811-norma-pl.html\">Decreto Legislativo 14\/26<\/a>.\u00a0O deputado Marcos Pereira (Republicanos-SP) relatou o texto em Plen\u00e1rio.<\/p>\n<p>O texto foi assinado em janeiro, junto com o acordo mais amplo, que tamb\u00e9m inclui temas pol\u00edticos e de coopera\u00e7\u00e3o.<\/p>\n<p>Segundo o governo brasileiro, o aumento de arrecada\u00e7\u00e3o com as transa\u00e7\u00f5es comerciais dever\u00e1 compensar a perda com impostos de importa\u00e7\u00e3o.<\/p>\n<p>Pa\u00edses do Mercosul e da Uni\u00e3o Europeia poder\u00e3o aprovar salvaguardas em rela\u00e7\u00e3o a determinados produtos para proteger produtores locais.<\/p>\n<figure class=\"materia__midia\" style=\"float: none; margin: 24px 0px;\" data-midia=\"1222119\"><img decoding=\"async\" src=\"https:\/\/www.camara.leg.br\/midias\/image\/2025\/11\/depositphotos-327335608-l-768x512.jpg\"\/><figcaption><span class=\"materia__legenda-imagem\">Benef\u00edcio \u00e9 destinado a quem est\u00e1 no Cad\u00danico<\/span> &#8211; <span class=\"materia__creditos-imagem\" style=\"color:#5f5f5e\">Foto: Depositphotos<\/span><\/figcaption><\/figure>\n<h3 class=\"ds-titulo-subsecao\">G\u00e1s do Povo<\/h3>\n<p>Entre as propostas aprovadas no primeiro semestre, tamb\u00e9m est\u00e1 a <a href=\"https:\/\/www.camara.leg.br\/noticias\/1241845-CAMARA-APROVA-MP-QUE-CRIA-O-PROGRAMA-GAS-DO-POVO-COM-BOTIJAO-GRATUITO-PARA-FAMILIAS-DE-BAIXA-RENDA\">Medida Provis\u00f3ria 1313\/25<\/a>, transformada na <a class=\"linkLegislacao\" href=\"https:\/\/www2.camara.gov.br\/legin\/fed\/lei\/2026\/lei-15348-13-fevereiro-2026-798716-norma-pl.html\" target=\"_blank\" rel=\"noopener noreferrer\">Lei 15.348\/26<\/a>, que criou a modalidade de retirada gratuita de botij\u00e3o em revenda cadastrada no programa G\u00e1s do Povo para fam\u00edlias de baixa renda.<\/p>\n<p>Fam\u00edlias com duas ou tr\u00eas pessoas poder\u00e3o retirar quatro botij\u00f5es por ano. Fam\u00edlias com quatro ou mais pessoas poder\u00e3o retirar seis.<\/p>\n<p>A partir de 2027, quando acabar a modalidade de ajuda em dinheiro, fam\u00edlias unipessoais n\u00e3o ter\u00e3o mais acesso ao botij\u00e3o subsidiado.<\/p>\n<p>Para acessar o benef\u00edcio nessa modalidade, a fam\u00edlia dever\u00e1 estar inscrita no Cadastro \u00danico para Programas Sociais (<span id=\"4330\" class=\"termoGlossario materia__glossario\" title=\"Instrumento de coleta de dados que identifica e caracteriza fam\u00edlias com renda mensal de at\u00e9 meio sal\u00e1rio m\u00ednimo por pessoa. Os dados obtidos por meio do Cad\u00danico s\u00e3o consolidados e utilizados, obrigatoriamente, na sele\u00e7\u00e3o de benefici\u00e1rios dos programas sociais do Governo Federal. Governos estaduais e municipais tamb\u00e9m podem usar os dados do cadastro para analisar o perfil socioecon\u00f4mico da popula\u00e7\u00e3o e, desse modo, implantar pol\u00edticas direcionadas \u00e0s necessidades locais.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\" style=\"color:#5f5f5e;border-bottom:none\">Cad\u00danico<\/span>) e ter renda mensal por pessoa de at\u00e9 meio sal\u00e1rio m\u00ednimo (R$ 759).<\/p>\n<figure class=\"materia__midia\" style=\"float: none; margin: 24px 0px;\" data-midia=\"1293237\"><img decoding=\"async\" src=\"https:\/\/www.camara.leg.br\/midias\/image\/2026\/07\/depositphotos-35237829-xl-768x521.jpg\"\/><figcaption><span class=\"materia__legenda-imagem\">Para ser considerado chocolate, o produto tem que ter 35% de s\u00f3lidos totais de cacau<\/span> &#8211; <span class=\"materia__creditos-imagem\" style=\"color:#5f5f5e\">Foto: Depositphotos<\/span><\/figcaption><\/figure>\n<h3 class=\"ds-titulo-subsecao\">Cacau no chocolate<\/h3>\n<p>As novas regras aprovadas pela C\u00e2mara para a quantidade m\u00ednima de cacau e seus compostos em produtos como chocolate e cacau em p\u00f3 tamb\u00e9m j\u00e1 viraram lei.<\/p>\n<p>Oriunda do <a href=\"https:\/\/www.camara.leg.br\/noticias\/1254741-CAMARA-APROVA-PROJETO-QUE-REGULAMENTA-PERCENTUAL-DE-CACAU-EM-CHOCOLATES\">Projeto de Lei 1769\/19<\/a>, do Senado, a <a class=\"linkLegislacao\" href=\"https:\/\/www2.camara.gov.br\/legin\/fed\/lei\/2026\/lei-15404-8-maio-2026-799087-norma-pl.html\" target=\"_blank\" rel=\"noopener noreferrer\">Lei 15.404\/26<\/a> s\u00f3 considera chocolate o produto que contenha pelo menos 35% de s\u00f3lidos totais de cacau.<\/p>\n<p>O texto tamb\u00e9m estabelece limites para manteiga de cacau, s\u00f3lidos secos desengordurados e outras gorduras vegetais autorizadas.<\/p>\n<p>O projeto foi relatado pelo deputado Daniel Almeida (PCdoB-BA).<\/p>\n<figure class=\"materia__midia\" style=\"float: none; margin: 24px 0px;\" data-midia=\"1293238\"><img decoding=\"async\" src=\"https:\/\/www.camara.leg.br\/midias\/image\/2026\/07\/depositphotos-345384998-xl-768x512.jpg\"\/><figcaption><span class=\"materia__legenda-imagem\">Presen\u00e7a de farmac\u00eautico ser\u00e1 obrigat\u00f3ria em drogarias de supermercados<\/span> &#8211; <span class=\"materia__creditos-imagem\" style=\"color:#5f5f5e\">Foto: Depositphotos<\/span><\/figcaption><\/figure>\n<h3 class=\"ds-titulo-subsecao\">Rem\u00e9dios em supermercados<\/h3>\n<p>Outro projeto aprovado pelos deputados, que j\u00e1 virou lei, trata do funcionamento de farm\u00e1cia dentro de supermercados.<\/p>\n<p>O <a href=\"https:\/\/www.camara.leg.br\/noticias\/1249270-CAMARA-APROVA-REGRAS-PARA-FUNCIONAMENTO-DE-FARMACIAS-DENTRO-DE-SUPERMERCADOS\">Projeto de Lei 2158\/23<\/a>, do Senado, convertido na <a class=\"linkLegislacao\" href=\"https:\/\/www2.camara.gov.br\/legin\/fed\/lei\/2026\/lei-15357-20-marco-2026-798834-norma-pl.html\" target=\"_blank\" rel=\"noopener noreferrer\">Lei 15.357\/26<\/a>, estabelece crit\u00e9rios para o funcionamento dessas drogarias e exige presen\u00e7a de farmac\u00eautico durante todo o hor\u00e1rio de funcionamento.<\/p>\n<p>O texto foi relatado pelo deputado Dr. Zacharias Calil (MDB-GO).<\/p>\n<figure class=\"materia__midia\" style=\"float: none; margin: 24px 0px;\" data-midia=\"1146296\"><img decoding=\"async\" src=\"https:\/\/www.camara.leg.br\/midias\/image\/2025\/04\/img201602151643336021337-768x512.jpg\" alt=\"Economia - exporta\u00e7\u00e3o - exporta\u00e7\u00f5es portos Paranagu\u00e1 (PR) cargas exporta\u00e7\u00f5es\"\/><figcaption><span class=\"materia__legenda-imagem\">Novo sistema deve aumentar seguran\u00e7a de empresas que atuam no mercado externo<\/span> &#8211; <span class=\"materia__creditos-imagem\" style=\"color:#5f5f5e\">Foto: APPA\/Divulga\u00e7\u00e3o<\/span><\/figcaption><\/figure>\n<h3 class=\"ds-titulo-subsecao\">Seguro para exporta\u00e7\u00e3o<\/h3>\n<p>Com a aprova\u00e7\u00e3o do <a href=\"https:\/\/www.camara.leg.br\/noticias\/1249267-CAMARA-APROVA-PROJETO-QUE-FACILITA-ACESSO-AO-SEGURO-DE-EXPORTACAO\">Projeto de Lei 6139\/23<\/a>, do Senado, a C\u00e2mara dos Deputados criou regras para facilitar o acesso ao seguro de exporta\u00e7\u00e3o.<\/p>\n<p>O texto, convertido na <a class=\"linkLegislacao\" href=\"https:\/\/www2.camara.gov.br\/legin\/fed\/lei\/2026\/lei-15359-24-marco-2026-798847-norma-pl.html\" target=\"_blank\" rel=\"noopener noreferrer\">Lei 15.359\/26<\/a>, prev\u00ea a cria\u00e7\u00e3o de um portal \u00fanico para centralizar pedidos de apoio oficial e permite o aproveitamento dos documentos apresentados pelo exportador em diferentes modalidades.<\/p>\n<p>O projeto foi relatado pelo deputado Arlindo Chinaglia (PT-SP).<\/p>\n<p>A nova lei tamb\u00e9m permite a cobertura do Fundo de Garantia \u00e0 Exporta\u00e7\u00e3o (FGE) em opera\u00e7\u00f5es de seguro de cr\u00e9dito de projetos de investimento produtivo de alta complexidade que sejam montados para fabricar bens e prestar servi\u00e7os a serem exportados.<strong>\u00a0<\/strong><\/p>\n<h3 class=\"ds-titulo-subsecao\">Prote\u00e7\u00e3o \u00e0 ind\u00fastria<\/h3>\n<p>Para proteger a ind\u00fastria nacional, a C\u00e2mara dos Deputados aprovou projeto de lei que amplia a margem de prefer\u00eancia para bens e servi\u00e7os nacionais em <span id=\"4297\" class=\"termoGlossario materia__glossario\" title=\"Processo utilizado pela administra\u00e7\u00e3o p\u00fablica para adquirir bens e servi\u00e7os de fornecedores privados nas melhores condi\u00e7\u00f5es poss\u00edveis. Pode ser pelo crit\u00e9rio do menor pre\u00e7o, da melhor t\u00e9cnica, ou do menor pre\u00e7o combinado com a melhor t\u00e9cnica. As modalidades de licita\u00e7\u00e3o previstas em lei s\u00e3o carta-convite, tomada de pre\u00e7os, concorr\u00eancia, preg\u00e3o, concurso e leil\u00e3o.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\" style=\"color:#5f5f5e;border-bottom:none\">licita\u00e7\u00f5es<\/span> p\u00fablicas.<\/p>\n<p>Assim, quando os pre\u00e7os do concorrente nacional forem 20% maiores que os dos concorrentes internacionais, dever\u00e1 ser dada prefer\u00eancia aos brasileiros. Atualmente, a margem \u00e9 de 10%.<\/p>\n<p>A margem atual de diferen\u00e7a de 20% passa para 30% quando bens e servi\u00e7os nacionais atenderem a crit\u00e9rios de sustentabilidade ou forem resultantes de desenvolvimento e inova\u00e7\u00e3o tecnol\u00f3gica no pa\u00eds.<\/p>\n<p>De autoria do deputado Heitor Schuch (PSD-RS), o Projeto de Lei 4133\/23 foi relatado pelo deputado Rodrigo Rollemberg (PSB-DF) e aguarda vota\u00e7\u00e3o no Senado.<\/p>\n<p>O texto tamb\u00e9m prev\u00ea pol\u00edticas de participa\u00e7\u00e3o exclusiva e exig\u00eancia de conte\u00fado nacional em leis relacionadas a concess\u00f5es e parcerias p\u00fablico-privadas.<strong>\u00a0<\/strong><\/p>\n<figure class=\"materia__midia\" style=\"float: none; margin: 24px 0px;\" data-midia=\"568794\"><img decoding=\"async\" src=\"https:\/\/www.camara.leg.br\/midias\/image\/2019\/08\/img20190530131640506-768x512.jpg\" alt=\"Economia - ind\u00fastria e com\u00e9rcio - f\u00e1bricas produ\u00e7\u00e3o industrial empregos PIB crescimento econ\u00f4mico (reciclagem de palets)\"\/><figcaption><span class=\"materia__legenda-imagem\">Lei permite que empresas deduzam do IR valores destinados a projetos de reciclagem<\/span> &#8211; <span class=\"materia__creditos-imagem\" style=\"color:#5f5f5e\">Foto: Alina Souza\/Pal\u00e1cio Piratini<\/span><\/figcaption><\/figure>\n<h3 class=\"ds-titulo-subsecao\">Incentivo a recicl\u00e1veis<\/h3>\n<p>Se virar lei, outra proposta aprovada pela C\u00e2mara dos Deputados tornar\u00e1 permanentes os incentivos \u00e0 ind\u00fastria de reciclagem previstos na <a class=\"linkLegislacao\" href=\"https:\/\/www2.camara.gov.br\/legin\/fed\/lei\/2021\/lei-14260-8-dezembro-2021-792071-norma-pl.html\" target=\"_blank\" rel=\"noopener noreferrer\">Lei 14.260\/21<\/a>.<\/p>\n<p>A proposta aumenta de 1% para 4% a dedu\u00e7\u00e3o do Imposto de Renda para pessoas jur\u00eddicas que destinarem recursos a projetos do setor.<\/p>\n<p>De autoria do deputado Ronaldo Nogueira (Republicanos-RS), o <a href=\"https:\/\/www.camara.leg.br\/noticias\/1289396-CAMARA-APROVA-PROJETO-QUE-TORNA-PERMANENTES-OS-INCENTIVOS-PARA-A-INDUSTRIA-DA-RECICLAGEM\">Projeto de Lei 1361\/25<\/a> foi relatado pelo deputado Arnaldo Jardim (Cidadania-SP) e tamb\u00e9m aguarda vota\u00e7\u00e3o no Senado.<\/p>\n<figure class=\"materia__midia\" style=\"float: none; margin: 24px 0px;\" data-midia=\"1195389\"><img decoding=\"async\" src=\"https:\/\/www.camara.leg.br\/midias\/image\/2025\/09\/img20220509103839961-768x576.jpg\" alt=\"Energia - combust\u00edvel - posto de gasolina - abastecimento - pre\u00e7o - economia - petr\u00f3leo\"\/><figcaption><span class=\"materia__legenda-imagem\">Quem aumentar injustificadamente o pre\u00e7o do combust\u00edvel poder\u00e1 ser preso<\/span> &#8211; <span class=\"materia__creditos-imagem\" style=\"color:#5f5f5e\">Foto: Jos\u00e9 Cruz\/Ag\u00eancia Brasil<\/span><\/figcaption><\/figure>\n<h3 class=\"ds-titulo-subsecao\">Pre\u00e7o do combust\u00edvel<\/h3>\n<p>Por fim, os deputados aprovaram um projeto que torna crime o aumento abusivo de pre\u00e7os de combust\u00edveis.<\/p>\n<p>O <a href=\"https:\/\/www.camara.leg.br\/noticias\/1274578-DEPUTADOS-APROVAM-PROJETO-QUE-TORNA-CRIME-AUMENTO-ABUSIVO-DE-PRECOS-DE-COMBUSTIVEIS\">Projeto de Lei 1625\/26<\/a>, do Poder Executivo, foi relatado pelo deputado Merlong Solano (PT-PI) e prev\u00ea pris\u00e3o de 2 a 4 anos e multa para quem aumentar, de forma artificial e sem justa causa, o pre\u00e7o dos combust\u00edveis.<\/p>\n<p>As penas ser\u00e3o aumentadas de 1\/3 at\u00e9 a metade se a conduta ocorrer em contexto de calamidade p\u00fablica, crise de abastecimento.<\/p>\n<p>O projeto aguarda vota\u00e7\u00e3o dos senadores.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1293096-retrospectiva-camara-aprovou-acordo-mercosul-uniao-europeia-e-novas-regras-para-exportacoes\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acordo ficou em negocia\u00e7\u00e3o por d\u00e9cadas no Congresso &#8211; Foto: Reprodu\u00e7\u00e3o No primeiro semestre de 2026, o destaque da \u00e1rea [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[34],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10592"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=10592"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10592\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/6909"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=10592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=10592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=10592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}