{"id":10298,"date":"2026-07-14T00:21:41","date_gmt":"2026-07-14T03:21:41","guid":{"rendered":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/comissao-aprova-criacao-de-simbolo-nacional-para-conscientizacao-sobre-doencas-raras-noticias\/"},"modified":"2026-07-14T00:21:41","modified_gmt":"2026-07-14T03:21:41","slug":"comissao-aprova-criacao-de-simbolo-nacional-para-conscientizacao-sobre-doencas-raras-noticias","status":"publish","type":"post","link":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/comissao-aprova-criacao-de-simbolo-nacional-para-conscientizacao-sobre-doencas-raras-noticias\/","title":{"rendered":"Comiss\u00e3o aprova cria\u00e7\u00e3o de s\u00edmbolo nacional para conscientiza\u00e7\u00e3o sobre doen\u00e7as raras &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"g-artigo__data-hora\">\n\t\t\t\t\t\t\t\t\t\t\t13\/07\/2026 &#8211; 10:09 \u00a0\n\t\t\t\t\t\t\t\t\t\t<\/p>\n<div id=\"image-container-1276383\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1276383\">\n<p><em>Vinicius Loures \/ C\u00e2mara dos Deputados<\/em><\/p>\n<p>Silvia Cristina recomendou a aprova\u00e7\u00e3o do projeto<\/p>\n<\/p><\/div>\n<p>A Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania da C\u00e2mara dos Deputados aprovou o Projeto de Lei 1643\/25, que reconhece o la\u00e7o multicolorido como s\u00edmbolo nacional da luta pelos direitos das pessoas com doen\u00e7as raras no Brasil.<\/p>\n<p>O texto segue para o Senado, caso n\u00e3o haja recurso para an\u00e1lise pelo Plen\u00e1rio.<\/p>\n<p>O s\u00edmbolo ter\u00e1 cinco cores: rosa, lil\u00e1s, azul, verde e amarelo.\u00a0Segundo o texto, as pontas come\u00e7am em rosa e passam gradualmente pelo lil\u00e1s, azul e verde, at\u00e9 chegar ao amarelo no centro do la\u00e7o.<\/p>\n<p>O uso do s\u00edmbolo ser\u00e1 opcional e sua aus\u00eancia n\u00e3o prejudica o exerc\u00edcio de direitos e garantias previstos em lei.<\/p>\n<p><strong>O s\u00edmbolo<\/strong><br \/>A autora da proposta, deputada Rosangela Moro (PL-SP), explicou que o la\u00e7o foi inspirado em s\u00edmbolo j\u00e1 adotado internacionalmente, o que favorece sua integra\u00e7\u00e3o ao movimento global de conscientiza\u00e7\u00e3o sobre doen\u00e7as raras.<\/p>\n<p>O projeto segue modelo semelhante ao do cord\u00e3o de girass\u00f3is, reconhecido pela <a class=\"linkLegislacao\" href=\"https:\/\/www2.camara.gov.br\/legin\/fed\/lei\/2023\/lei-14624-17-julho-2023-794443-norma-pl.html\" target=\"_blank\" rel=\"noopener noreferrer\">Lei 14.624\/23<\/a>, como s\u00edmbolo oficial das defici\u00eancias ocultas.<\/p>\n<p><strong>Doen\u00e7as raras<\/strong><br \/>As doen\u00e7as raras, embora individualmente pouco prevalentes, afetam milh\u00f5es de brasileiros. A deputada destaca que essa popula\u00e7\u00e3o enfrenta diagn\u00f3stico frequentemente tardio e barreiras de acesso ao tratamento, o que a coloca em situa\u00e7\u00e3o de vulnerabilidade.<\/p>\n<p>A proposta tem respaldo na Pol\u00edtica Nacional de Aten\u00e7\u00e3o Integral \u00e0s Pessoas com Doen\u00e7as Raras, institu\u00edda pela Portaria 199\/14 do Minist\u00e9rio da Sa\u00fade.<\/p>\n<p>O Brasil j\u00e1 conta com o Dia Nacional das Doen\u00e7as Raras (<a class=\"linkLegislacao\" href=\"https:\/\/www2.camara.gov.br\/legin\/fed\/lei\/2018\/lei-13693-10-julho-2018-786958-norma-pl.html\" target=\"_blank\" rel=\"noopener noreferrer\">Lei 13.693\/18<\/a>) e o Dia Nacional da Informa\u00e7\u00e3o, Capacita\u00e7\u00e3o e Pesquisa sobre Doen\u00e7as Raras (<a class=\"linkLegislacao\" href=\"https:\/\/www2.camara.gov.br\/legin\/fed\/lei\/2023\/lei-14593-2-junho-2023-794258-norma-pl.html\" target=\"_blank\" rel=\"noopener noreferrer\">Lei 14.593\/23<\/a>), mas ainda n\u00e3o possui um s\u00edmbolo oficial para a causa.<\/p>\n<p>Para Rosangela Moro, a ado\u00e7\u00e3o do la\u00e7o multicolorido ajudar\u00e1 a dar mais visibilidade \u00e0s pessoas com doen\u00e7as raras e a fortalecer pol\u00edticas p\u00fablicas voltadas a esse p\u00fablico.<\/p>\n<p><strong>Parecer a favor<\/strong><br \/>Segundo a relatora, deputada Silvia Cristina (PP-RO), as doen\u00e7as raras s\u00e3o um relevante desafio para o sistema p\u00fablico de sa\u00fade, demandando pol\u00edticas p\u00fablicas voltadas ao diagn\u00f3stico precoce, ao acesso ao tratamento e \u00e0 promo\u00e7\u00e3o da inclus\u00e3o social.<\/p>\n<p>&#8220;Iniciativas legislativas de conscientiza\u00e7\u00e3o e visibilidade social mostram-se leg\u00edtimas e adequadas ao interesse p\u00fablico&#8221;, afirmou.<\/p>\n<p>\u00a0<\/p>\n<p>\t\t\t\t<iframe class=\"infografico-container\" style=\"width: 100%; height: 100%;\" src=\"https:\/\/www.camara.leg.br\/internet\/agencia\/infograficos-html5\/doencas-raras\/index.html\" frameborder=\"0\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Reportagem &#8211; Tiago Miranda<br \/>Edi\u00e7\u00e3o &#8211; Natalia Doederlein<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1289815-comissao-aprova-criacao-de-simbolo-nacional-para-conscientizacao-sobre-doencas-raras\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>13\/07\/2026 &#8211; 10:09 \u00a0 Vinicius Loures \/ C\u00e2mara dos Deputados Silvia Cristina recomendou a aprova\u00e7\u00e3o do projeto A Comiss\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[26],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10298"}],"collection":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=10298"}],"version-history":[{"count":0,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/10298\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/9051"}],"wp:attachment":[{"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=10298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=10298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosantaclara.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=10298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}